{"id":3723,"date":"2018-08-03T07:30:57","date_gmt":"2018-08-03T00:30:57","guid":{"rendered":"https:\/\/www.bolttech.co.th\/blog?p=3723"},"modified":"2018-08-03T07:30:57","modified_gmt":"2018-08-03T00:30:57","slug":"%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3","status":"publish","type":"post","link":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3","title":{"rendered":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 ?"},"content":{"rendered":"<p>\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e0b\u0e35\u0e23\u0e35\u0e22\u0e4c\u0e08\u0e35\u0e19\u0e2e\u0e2d\u0e15\u0e2e\u0e34\u0e15\u0e01\u0e31\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e40\u0e2b\u0e47\u0e19\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e22\u0e32\u0e01\u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e07 \u0e41\u0e27\u0e30\u0e2a\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e2b\u0e25\u0e48\u0e2d-\u0e2a\u0e32\u0e27\u0e2a\u0e27\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e14\u0e19\u0e21\u0e31\u0e07\u0e01\u0e23\u0e2a\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e42\u0e25\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e21\u0e23\u0e14\u0e01\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e02\u0e19\u0e32\u0e19\u0e19\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\u0e1b\u0e48\u0e32\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e22\u0e31\u0e07\u0e04\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e14\u0e31\u0e49\u0e07\u0e40\u0e14\u0e34\u0e21\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e44\u0e14\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e14\u0e35 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e19\u0e48\u0e2b\u0e4c\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27<br \/>\n\u0e43\u0e04\u0e23\u0e01\u0e33\u0e25\u0e31\u0e07\u0e21\u0e35\u0e41\u0e1e\u0e25\u0e19\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49 Frank \u0e02\u0e2d\u0e41\u0e19\u0e30\u0e19\u0e33 <strong><span style=\"color: #ff6600;\">4 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e2a\u0e1a\u0e32\u0e22\u0e43\u0e08\u0e41\u0e1a\u0e1a\u0e44\u0e23\u0e49\u0e01\u0e31\u0e07\u0e27\u0e25<\/span><\/strong> \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e40\u0e2a\u0e35\u0e22\u0e40\u0e27\u0e25\u0e32 \u0e40\u0e23\u0e32\u0e21\u0e32\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e31\u0e19<\/p>\n<h2><span style=\"color: #0000ff;\"><b>1. \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e17\u0e23\u0e34\u0e1b\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e01\u0e32\u0e23\u0e44\u0e1b\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07\u0e04\u0e37\u0e2d\u0e24\u0e14\u0e39\u0e43\u0e1a\u0e44\u0e21\u0e49\u0e1c\u0e25\u0e34 (\u0e1b\u0e25\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e40\u0e21\u0e29\u0e32\u0e22\u0e19\u0e16\u0e36\u0e07\u0e15\u0e49\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19) \u0e41\u0e25\u0e30\u0e24\u0e14\u0e39\u0e43\u0e1a\u0e44\u0e21\u0e49\u0e23\u0e48\u0e27\u0e07 (\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\u0e16\u0e36\u0e07\u0e15\u0e38\u0e25\u0e32\u0e04\u0e21)<br \/>\n\u0e14\u0e49\u0e27\u0e22\u0e27\u0e34\u0e27\u0e17\u0e34\u0e27\u0e17\u0e31\u0e28\u0e19\u0e4c\u0e2d\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e19\u0e48\u0e32\u0e44\u0e1b\u0e40\u0e22\u0e37\u0e2d\u0e19\u0e40\u0e01\u0e34\u0e4a\u0e19 !! <span style=\"color: #ff6600;\"><em><strong>\u0e41\u0e2b\u0e21..\u0e08\u0e30\u0e44\u0e1b\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e31\u0e49\u0e07\u0e17\u0e35\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e17\u0e23\u0e34\u0e1b\u0e40\u0e15\u0e47\u0e21\u0e44\u0e2b\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e17\u0e48\u0e32\u0e17\u0e48\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e40\u0e01\u0e4b\u0e40\u0e25\u0e34\u0e28 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48<\/strong><\/em><\/span><br \/>\n<span style=\"color: #ff6600;\"><em><strong> \u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e2b\u0e49\u0e41\u0e19\u0e48\u0e19\u0e41\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21<\/strong><\/em><\/span><\/span><br \/>\n<span style=\"font-weight: 400;\">\u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e41\u0e22\u0e07\u0e0b\u0e35\u0e40\u0e01\u0e35\u0e22\u0e07-\u0e2d\u0e39\u0e48\u0e2b\u0e25\u0e07, \u0e0a\u0e21\u0e16\u0e49\u0e33\u0e1d\u0e39\u0e2b\u0e22\u0e07\u0e15\u0e49\u0e07, \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e32\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e2b\u0e25\u0e38\u0e21\u0e1f\u0e49\u0e32\u0e2a\u0e30\u0e1e\u0e32\u0e19\u0e21\u0e31\u0e07\u0e01\u0e23 (\u0e40\u0e17\u0e35\u0e22\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e0b\u0e32\u0e19\u0e40\u0e09\u0e35\u0e22\u0e27) \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48<br \/>\n\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2d\u0e39\u0e48\u0e2b\u0e25\u0e07, \u0e07\u0e32\u0e19\u0e41\u0e01\u0e30\u0e2a\u0e25\u0e31\u0e01\u0e2b\u0e34\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e15\u0e49\u0e32\u0e08\u0e39\u0e4b \u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e07\u0e32\u0e21\u0e02\u0e2d\u0e07\u0e1e\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e19\u0e32\u0e25\u0e31\u0e17\u0e18\u0e34\u0e40\u0e15\u0e4b\u0e32\u0e41\u0e25\u0e30\u0e02\u0e07\u0e08\u0e37\u0e49\u0e2d <strong><em><span style=\"color: #ff6600;\">\u0e2b\u0e49\u0e32\u0e21\u0e1e\u0e25\u0e32\u0e14\u0e01\u0e31\u0e1a\u0e08\u0e38\u0e14\u0e0a\u0e21\u0e27\u0e34\u0e27 Yi Ke Shu \u0e2b\u0e23\u0e37\u0e2d<\/span><\/em><\/strong><br \/>\n<strong><em><span style=\"color: #ff6600;\"> One Tree \u0e14\u0e49\u0e32\u0e19\u0e1a\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e17\u0e37\u0e2d\u0e01\u0e40\u0e02\u0e32 Nanshan \u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e17\u0e31\u0e28\u0e19\u0e35\u0e22\u0e20\u0e32\u0e1e\u0e2d\u0e31\u0e19\u0e07\u0e14\u0e07\u0e32\u0e21\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07\u0e22\u0e32\u0e21\u0e04\u0e48\u0e33\u0e04\u0e37\u0e19<\/span> <\/em><\/strong>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2d\u0e37\u0e48\u0e19 \u0e46<br \/>\n\u0e2d\u0e35\u0e01\u0e40\u0e1e\u0e35\u0e22\u0e1a !! \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e15\u0e32\u0e21\u0e43\u0e08\u0e0a\u0e2d\u0e1a \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e17\u0e35\u0e48\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07\u0e01\u0e47\u0e40\u0e14\u0e47\u0e14\u0e43\u0e0a\u0e48\u0e22\u0e48\u0e2d\u0e22<\/span><br \/>\n&nbsp;<br \/>\n<img class=\"size-full wp-image-3729 aligncenter\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2018\/08\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07-\u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19-\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07-body2.png\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07-featured\" width=\"768\" height=\"503\" \/><br \/>\n&nbsp;<br \/>\n\u0e40\u0e08\u0e2d\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e0b\u0e25\u0e1f\u0e35\u0e48\u0e2a\u0e34\u0e08\u0e49\u0e30 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e0a\u0e38\u0e14\u0e08\u0e35\u0e19\u0e42\u0e1a\u0e23\u0e32\u0e13 \u0e41\u0e25\u0e30\u0e14\u0e31\u0e4a\u0e19\u0e42\u0e1e\u0e2a\u0e17\u0e48\u0e32\u0e40\u0e1e\u0e25\u0e34\u0e19\u0e40\u0e01\u0e34\u0e19\u0e2b\u0e49\u0e32\u0e21\u0e43\u0e08\u0e44\u0e1b\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e41\u0e25\u0e30\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e44\u0e21\u0e48\u0e04\u0e32\u0e14\u0e1d\u0e31\u0e19\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e02\u0e32\u0e2b\u0e31\u0e01 \u0e41\u0e02\u0e19\u0e2b\u0e31\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e1a\u0e32\u0e14\u0e40\u0e08\u0e47\u0e1a !! \u0e07\u0e37\u0e2d... \u0e2d\u0e31\u0e19\u0e19\u0e35\u0e49 <span style=\"color: #0000ff;\"><strong>\u201c\u0e41\u0e22\u0e48\u0e40\u0e25\u0e22\u0e19\u0e30\u201d<\/strong><\/span>\u00a0\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e04\u0e48\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e41\u0e1e\u0e07\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e41\u0e1c\u0e19\u0e01\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e32\u0e27\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34<br \/>\n\u0e2d\u0e31\u0e19\u0e19\u0e35\u0e49 Frank \u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e41\u0e0a\u0e48\u0e07\u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e14\u0e19\u0e30\u0e08\u0e4a\u0e30 \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e48\u0e27\u0e07\u0e04\u0e38\u0e13\u0e1c\u0e39\u0e49\u0e2d\u0e48\u0e32\u0e19 \u0e41\u0e25\u0e30\u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1f\u0e31\u0e07\u0e40\u0e09\u0e22 \u0e46 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e40\u0e27\u0e25\u0e32 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e0b\u0e37\u0e49\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e44\u0e27\u0e49\u0e40\u0e16\u0e34\u0e14\u0e08\u0e30\u0e40\u0e01\u0e34\u0e14\u0e1c\u0e25 \u0e0a\u0e48\u0e27\u0e22\u0e14\u0e39\u0e41\u0e25\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e41\u0e1a\u0e1a 24\/7 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2a\u0e19\u0e38\u0e01 \u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<span style=\"color: #ff6600;\"><strong> \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e23\u0e21\u0e18\u0e23\u0e23\u0e21\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e19\u0e43\u0e08\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e2a\u0e48\u0e27\u0e19\u0e1a\u0e38\u0e04\u0e04\u0e25\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32 Frank \u0e44\u0e14\u0e49 \u0e40\u0e1a\u0e35\u0e49\u0e22\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e27\u0e31\u0e19\u0e25\u0e30 3 \u0e1a\u0e32\u0e17\u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19<\/strong><\/span><\/p>\n<h2><span style=\"color: #0000ff;\"><b>2. \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e14\u0e49\u0e27\u0e22\u0e2d\u0e32\u0e13\u0e32\u0e40\u0e02\u0e15\u0e01\u0e27\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e44\u0e1e\u0e28\u0e32\u0e25 \u0e01\u0e32\u0e23\u0e08\u0e2d\u0e07\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e30\u0e25\u0e38\u0e22\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e21\u0e32\u0e01 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e04\u0e37\u0e2d \u0e04\u0e38\u0e13\u0e04\u0e27\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e08\u0e2d\u0e07\u0e44\u0e27\u0e49\u0e01\u0e48\u0e2d\u0e19\u0e0a\u0e31\u0e27\u0e23\u0e4c\u0e01\u0e27\u0e48\u0e32<br \/>\n\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e01\u0e27\u0e49\u0e32\u0e07\u0e02\u0e27\u0e32\u0e07\u0e21\u0e35\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e0a\u0e49 \u0e41\u0e15\u0e48\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e07\u0e07 \u0e46 \u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e46 \u00a0\u0e2b\u0e23\u0e37\u0e2d\u0e16\u0e49\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e14\u0e49\u0e27\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e20\u0e39\u0e40\u0e02\u0e32\u0e41\u0e25\u0e30\u0e40\u0e19\u0e34\u0e19\u0e40\u0e02\u0e32 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e17\u0e49\u0e32\u0e17\u0e32\u0e22 \u0e40\u0e2b\u0e47\u0e19\u0e27\u0e48\u0e32\u0e21\u0e35\u0e16\u0e19\u0e19\u0e1a\u0e19\u0e14\u0e32\u0e14\u0e1f\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e15\u0e36\u0e01\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e04\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e16\u0e44\u0e1f\u0e1f\u0e49\u0e32\u0e42\u0e21\u0e42\u0e19\u0e40\u0e23\u0e25\u0e17\u0e30\u0e25\u0e38\u0e15\u0e36\u0e01 <span style=\"color: #ff6600;\"><strong><em>\u0e2d\u0e37\u0e21... \u0e44\u0e21\u0e48\u0e18\u0e23\u0e23\u0e21\u0e14\u0e32\u0e08\u0e23\u0e34\u0e07 \u0e46 \u0e40\u0e0a\u0e35\u0e22\u0e27<\/em> <\/strong><\/span>\u00a0<\/span><br \/>\n<span style=\"font-weight: 400;\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01 \u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19\u0e28\u0e36\u0e01\u0e29\u0e32\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e15\u0e23\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e41\u0e25\u0e49\u0e27 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2a\u0e32\u0e22\u0e15\u0e34\u0e2a\u0e17\u0e4c\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e32\u0e01\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e2d\u0e01\u0e17\u0e23\u0e34\u0e1b\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e25\u0e22 \u0e04\u0e38\u0e13\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 (PA) \u0e08\u0e32\u0e01\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e1e\u0e01\u0e44\u0e27\u0e49\u0e14\u0e49\u0e27\u0e22 <\/span><\/p>\n<ul>\n<li><strong>\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e04\u0e38\u0e13\u0e08\u0e32\u0e01\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19 <\/strong><\/li>\n<li><strong>\u0e01\u0e23\u0e13\u0e35\u0e40\u0e2a\u0e35\u0e22\u0e0a\u0e35\u0e27\u0e34\u0e15 \u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e22\u0e15\u0e32 \u0e01\u0e23\u0e13\u0e35\u0e17\u0e38\u0e1e\u0e1e\u0e25\u0e20\u0e32\u0e1e\u0e16\u0e32\u0e27\u0e23<\/strong><\/li>\n<li><strong>\u0e04\u0e48\u0e32\u0e23\u0e31\u0e01\u0e29\u0e32\u0e1e\u0e22\u0e32\u0e1a\u0e32\u0e25\u0e08\u0e32\u0e01\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e19\u0e15\u0e48\u0e32\u0e07\u0e41\u0e14\u0e19<\/strong><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u0e2d\u0e22\u0e48\u0e32\u0e25\u0e37\u0e21\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e19\u0e31\u0e49\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e44\u0e27\u0e49\u0e01\u0e48\u0e2d\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e41\u0e01\u0e49 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e49\u0e32\u0e41\u0e22\u0e48\u0e08\u0e30\u0e41\u0e01\u0e49\u0e44\u0e21\u0e48\u0e17\u0e31\u0e19 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e2a\u0e38\u0e20\u0e32\u0e29\u0e34\u0e15\u0e44\u0e17\u0e22 \u201c\u0e27\u0e31\u0e27\u0e2b\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27\u0e25\u0e49\u0e2d\u0e21\u0e04\u0e2d\u0e01\u201d \u0e2d\u0e31\u0e19\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e14\u0e35\u0e41\u0e19\u0e48 \u0e46\u00a0\u00a0<\/span><br \/>\n&nbsp;<br \/>\n<img class=\"size-full wp-image-1285 aligncenter\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2016\/11\/q_start.png\" alt=\"q_start\" width=\"187\" height=\"134\" \/><\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #ff6600;\"><em>\u0e2d\u0e22\u0e48\u0e32\u0e23\u0e2d\u0e43\u0e2b\u0e49\u0e27\u0e31\u0e27\u0e2b\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27\u0e25\u0e49\u0e2d\u0e21\u0e04\u0e2d\u0e01<br \/>\n\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e27\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07<br \/>\n\u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e15\u0e34\u0e14\u0e15\u0e31\u0e27\u0e44\u0e27\u0e49 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e04\u0e38\u0e13<\/em><\/span><\/h2>\n<p style=\"text-align: center;\"><img class=\"size-full wp-image-1284 aligncenter\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2016\/11\/q_end.png\" alt=\"q_end\" width=\"186\" height=\"133\" \/><\/p>\n<p>&nbsp;<br \/>\n<img class=\"size-full wp-image-3730 aligncenter\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2018\/08\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07-\u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19-\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07-body3.png\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07\" width=\"768\" height=\"503\" \/><br \/>\n&nbsp;<\/p>\n<h2><span style=\"color: #0000ff;\"><b>3. \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 (PA)<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e40\u0e1e\u0e23\u0e32\u0e30 Frank \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e48\u0e27\u0e07\u0e17\u0e38\u0e01\u0e04\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e01\u0e25\u0e48\u0e32\u0e27\u0e21\u0e32\u0e01\u0e32\u0e23\u0e08\u0e30\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e35\u0e48\u0e43\u0e14\u0e43\u0e19\u0e42\u0e25\u0e01\u0e01\u0e32\u0e23\u0e0b\u0e37\u0e49\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49<br \/>\n\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e21\u0e32\u0e01\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e23\u0e21\u0e18\u0e23\u0e23\u0e21\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e14\u0e39\u0e41\u0e25\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e21\u0e48\u0e2a\u0e30\u0e14\u0e38\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e27\u0e34\u0e19\u0e32\u0e17\u0e35 <\/span><br \/>\n<span style=\"font-weight: 400;\">\u0e41\u0e15\u0e48\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e21\u0e38\u0e48\u0e07\u0e40\u0e19\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e20\u0e31\u0e22\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23<br \/>\n\u0e04\u0e27\u0e32\u0e21\u0e14\u0e39\u0e41\u0e25\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e1a\u0e04\u0e23\u0e31\u0e19\u0e40\u0e15\u0e47\u0e21\u0e1e\u0e34\u0e01\u0e31\u0e14 <\/span><span style=\"color: #333399;\"><a style=\"color: #333399;\" href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%94%E0%B8%B4%E0%B8%99%E0%B8%97%E0%B8%B2%E0%B8%87\" target=\"_blank\" rel=\"noopener\"><strong>\u0e41\u0e19\u0e30\u0e19\u0e33\u0e0b\u0e37\u0e49\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07<\/strong><\/a><\/span><span style=\"font-weight: 400;\">\u0e23\u0e48\u0e27\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e47<span style=\"color: #008000;\"><span style=\"color: #ff6600;\"> <strong>\u201c\u0e40\u0e27\u0e34\u0e23\u0e4c\u0e04\u201d\u00a0<\/strong> <\/span>\u00a0<\/span><\/span><br \/>\n&nbsp;<br \/>\n<img class=\"size-full wp-image-3728 aligncenter\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2018\/08\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07-\u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19-\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07-body1.png\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07\" width=\"768\" height=\"503\" \/><br \/>\n&nbsp;<\/p>\n<h2><span style=\"color: #0000ff;\"><b>4. \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e42\u0e25\u0e49\u0e14!!<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e2b\u0e32\u0e01\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e23\u0e1a\u0e2b\u0e21\u0e14\u0e41\u0e25\u0e49\u0e27 \u0e21\u0e32\u0e16\u0e36\u0e07\u0e02\u0e49\u0e2d\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22 !!!! \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e2d\u0e2d\u0e01\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e40\u0e1b\u0e34\u0e14\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e43\u0e2b\u0e21\u0e48 \u0e46 \u0e0a\u0e32\u0e23\u0e4c\u0e08\u0e41\u0e1a\u0e15\u0e40\u0e15\u0e2d\u0e23\u0e35\u0e48\u0e0a\u0e35\u0e27\u0e34\u0e15<br \/>\n\u0e41\u0e25\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e25\u0e37\u0e21\u0e0b\u0e37\u0e49\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e44\u0e27\u0e49\u0e14\u0e39\u0e41\u0e25\u0e04\u0e38\u0e13\u0e41\u0e25\u0e30\u0e04\u0e19\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e23\u0e31\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e0b\u0e1f\u0e15\u0e35\u0e49 \u0e14\u0e39\u0e41\u0e25\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38<br \/>\n\u0e0a\u0e48\u0e27\u0e22\u0e0a\u0e14\u0e40\u0e0a\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e32\u0e14\u0e40\u0e08\u0e47\u0e1a \u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e15\u0e32\u0e21\u0e01\u0e23\u0e21\u0e18\u0e23\u0e23\u0e21\u0e4c\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e0b\u0e37\u0e49\u0e2d\u0e25\u0e48\u0e30\u0e08\u0e49\u0e32 \u0e14\u0e49\u0e27\u0e22\u0e23\u0e31\u0e01\u0e41\u0e25\u0e30\u0e2b\u0e48\u0e27\u0e07\u0e43\u0e22<\/span><br \/>\n<span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48<strong><a href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%AD%E0%B8%B8%E0%B8%9A%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B9%80%E0%B8%AB%E0%B8%95%E0%B8%B8%E0%B8%AA%E0%B9%88%E0%B8%A7%E0%B8%99%E0%B8%9A%E0%B8%B8%E0%B8%84%E0%B8%84%E0%B8%A5\" target=\"_blank\" rel=\"noopener\">\u0e2a\u0e19\u0e43\u0e08\u0e0b\u0e37\u0e49\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e31\u0e1a Frank.co.th<\/a> <\/strong>\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e16\u0e39\u0e01\u0e42\u0e2b\u0e27\u0e15\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a 1 \u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22<br \/>\n\u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e38\u0e13\u0e40\u0e0a\u0e47\u0e01\u0e40\u0e1a\u0e35\u0e49\u0e22\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e07\u0e48\u0e32\u0e22 \u0e46 \u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e40\u0e27\u0e25\u0e32 \u0e40\u0e04\u0e25\u0e21\u0e40\u0e23\u0e47\u0e27 \u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e17\u0e35\u0e48\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22<br \/>\n\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e31\u0e1a<a href=\"https:\/\/www.bolttech.co.th\/penguin-privilege\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"color: #ff6600;\">\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1e\u0e34\u0e40\u0e28\u0e29 Penguin Privilege<\/span><\/strong><\/a> \u0e14\u0e35\u0e25\u0e14\u0e35 \u0e46 \u0e42\u0e1b\u0e23\u0e42\u0e21\u0e0a\u0e31\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e25\u0e14\u0e17\u0e35\u0e48\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e17\u0e38\u0e01\u0e44\u0e25\u0e1f\u0e4c\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e27\u0e48\u0e32 \u0e04\u0e38\u0e49\u0e21\u0e04\u0e48\u0e32 !!<\/span><br \/>\n<b>\u0e41\u0e2b\u0e25\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25: <\/b><a href=\"http:\/\/www.chinadaily.com.cn\/a\/201804\/30\/WS5ae67c1da3105cdcf651b458.html\" target=\"_blank\" rel=\"noopener\"><i><span style=\"font-weight: 400;\">chinadaily.com.cn<\/span><\/i><\/a><br \/>\n<strong>Content by<\/strong> Butter Cutter<br \/>\n&nbsp;<br \/>\n<a href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%AD%E0%B8%B8%E0%B8%9A%E0%B8%B1%E0%B8%95%E0%B8%B4%E0%B9%80%E0%B8%AB%E0%B8%95%E0%B8%B8%E0%B8%AA%E0%B9%88%E0%B8%A7%E0%B8%99%E0%B8%9A%E0%B8%B8%E0%B8%84%E0%B8%84%E0%B8%A5\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone wp-image-10939 size-full\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2020\/03\/Banner-\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38-01.jpg\" alt=\"\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\" width=\"870\" height=\"299\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e0b\u0e35\u0e23\u0e35\u0e22\u0e4c\u0e08\u0e35\u0e19\u0e2e\u0e2d\u0e15\u0e2e\u0e34\u0e15\u0e01\u0e31\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e40\u0e2b\u0e47\u0e19\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e22\u0e32\u0e01\u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e07 \u0e41\u0e27\u0e30\u0e2a\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e2b\u0e25\u0e48\u0e2d-\u0e2a\u0e32\u0e27\u0e2a\u0e27\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e14\u0e19\u0e21\u0e31\u0e07\u0e01\u0e23\u0e2a\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e42\u0e25\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e21\u0e23\u0e14\u0e01\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e02\u0e19\u0e32\u0e19\u0e19\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\u0e1b\u0e48\u0e32\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e22\u0e31\u0e07\u0e04\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27<\/p>\n","protected":false},"author":20,"featured_media":3731,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[2062],"tags":[1787,1584,1788,1096],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.0 (Yoast SEO v20.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 ? - Bolttech Blog - News &amp; Updates<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bolttech.co.th\/blog\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07-\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 ?\" \/>\n<meta property=\"og:description\" content=\"\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e0b\u0e35\u0e23\u0e35\u0e22\u0e4c\u0e08\u0e35\u0e19\u0e2e\u0e2d\u0e15\u0e2e\u0e34\u0e15\u0e01\u0e31\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e40\u0e2b\u0e47\u0e19\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e22\u0e32\u0e01\u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e07 \u0e41\u0e27\u0e30\u0e2a\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e2b\u0e25\u0e48\u0e2d-\u0e2a\u0e32\u0e27\u0e2a\u0e27\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e14\u0e19\u0e21\u0e31\u0e07\u0e01\u0e23\u0e2a\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e42\u0e25\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e21\u0e23\u0e14\u0e01\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e02\u0e19\u0e32\u0e19\u0e19\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\u0e1b\u0e48\u0e32\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e22\u0e31\u0e07\u0e04\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bolttech.co.th\/blog\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07-\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\" \/>\n<meta property=\"og:site_name\" content=\"Bolttech Blog - News &amp; Updates\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-03T00:30:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2018\/08\/\u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19-\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07-featured.png\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"503\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Butter Cutter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@bolttechTH\" \/>\n<meta name=\"twitter:site\" content=\"@bolttechTH\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Butter Cutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3\",\"url\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3\",\"name\":\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 ? - Bolttech Blog - News &amp; Updates\",\"isPartOf\":{\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#website\"},\"datePublished\":\"2018-08-03T00:30:57+00:00\",\"dateModified\":\"2018-08-03T00:30:57+00:00\",\"author\":{\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bolttech.co.th\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#website\",\"url\":\"https:\/\/www.bolttech.co.th\/blog\/\",\"name\":\"Bolttech Blog - News &amp; Updates\",\"description\":\"Bolttech Blog - News &amp; Updates\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bolttech.co.th\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9\",\"name\":\"Butter Cutter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g\",\"caption\":\"Butter Cutter\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 ? - Bolttech Blog - News &amp; Updates","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bolttech.co.th\/blog\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07-\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23","og_locale":"th_TH","og_type":"article","og_title":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 ?","og_description":"\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e35\u0e49\u0e0b\u0e35\u0e23\u0e35\u0e22\u0e4c\u0e08\u0e35\u0e19\u0e2e\u0e2d\u0e15\u0e2e\u0e34\u0e15\u0e01\u0e31\u0e19\u0e17\u0e31\u0e48\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e40\u0e2b\u0e47\u0e19\u0e41\u0e25\u0e49\u0e27\u0e2d\u0e22\u0e32\u0e01\u0e15\u0e32\u0e21\u0e23\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e07 \u0e41\u0e27\u0e30\u0e2a\u0e48\u0e2d\u0e07\u0e2b\u0e19\u0e38\u0e48\u0e21\u0e2b\u0e25\u0e48\u0e2d-\u0e2a\u0e32\u0e27\u0e2a\u0e27\u0e22\u0e41\u0e2b\u0e48\u0e07\u0e41\u0e14\u0e19\u0e21\u0e31\u0e07\u0e01\u0e23\u0e2a\u0e31\u0e01\u0e2b\u0e19\u0e48\u0e2d\u0e22 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e42\u0e25\u0e40\u0e04\u0e0a\u0e31\u0e19\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e21\u0e23\u0e14\u0e01\u0e42\u0e25\u0e01\u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e02\u0e19\u0e32\u0e19\u0e19\u0e32\u0e21\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\u0e1b\u0e48\u0e32\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e43\u0e15\u0e49\u0e02\u0e2d\u0e07\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e23\u0e31\u0e10\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e0a\u0e19\u0e08\u0e35\u0e19 \u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e22\u0e31\u0e07\u0e04\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e27\u0e34\u0e16\u0e35\u0e0a\u0e35\u0e27","og_url":"https:\/\/www.bolttech.co.th\/blog\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07-\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23","og_site_name":"Bolttech Blog - News &amp; Updates","article_published_time":"2018-08-03T00:30:57+00:00","og_image":[{"width":768,"height":503,"url":"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2018\/08\/\u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19-\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07-featured.png","type":"image\/png"}],"author":"Butter Cutter","twitter_card":"summary_large_image","twitter_creator":"@bolttechTH","twitter_site":"@bolttechTH","twitter_misc":{"Written by":"Butter Cutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3","url":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3","name":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 ? - Bolttech Blog - News &amp; Updates","isPartOf":{"@id":"https:\/\/www.bolttech.co.th\/blog\/#website"},"datePublished":"2018-08-03T00:30:57+00:00","dateModified":"2018-08-03T00:30:57+00:00","author":{"@id":"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9"},"breadcrumb":{"@id":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%89%e0%b8%87%e0%b8%8a%e0%b8%b4%e0%b9%88%e0%b8%87-%e0%b9%80%e0%b8%95%e0%b8%a3%e0%b8%b5%e0%b8%a2%e0%b8%a1%e0%b8%ad%e0%b8%b0%e0%b9%84%e0%b8%a3#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bolttech.co.th\/blog"},{"@type":"ListItem","position":2,"name":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e09\u0e07\u0e0a\u0e34\u0e48\u0e07 \u0e15\u0e30\u0e25\u0e38\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e08\u0e35\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 ?"}]},{"@type":"WebSite","@id":"https:\/\/www.bolttech.co.th\/blog\/#website","url":"https:\/\/www.bolttech.co.th\/blog\/","name":"Bolttech Blog - News &amp; Updates","description":"Bolttech Blog - News &amp; Updates","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bolttech.co.th\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9","name":"Butter Cutter","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g","caption":"Butter Cutter"}}]}},"_links":{"self":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts\/3723"}],"collection":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/comments?post=3723"}],"version-history":[{"count":0,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts\/3723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/media\/3731"}],"wp:attachment":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/media?parent=3723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/categories?post=3723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/tags?post=3723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}