{"id":7177,"date":"2019-07-22T07:19:51","date_gmt":"2019-07-22T00:19:51","guid":{"rendered":"https:\/\/www.bolttech.co.th\/blog?p=7177"},"modified":"2023-08-10T17:21:28","modified_gmt":"2023-08-10T10:21:28","slug":"%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99","status":"publish","type":"post","link":"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99","title":{"rendered":"\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e44\u0e21\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e43\u0e0a\u0e49 <\/span><span style=\"color: #800080;\"><a style=\"color: #800080;\" href=\"https:\/\/www.bolttech.co.th\/blog\/diy-\u0e27\u0e34\u0e18\u0e35\u0e25\u0e1a\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\" target=\"_blank\" rel=\"noopener\">\u0e27\u0e34\u0e18\u0e35\u0e25\u0e1a\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e1a\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e41\u0e1a\u0e1a DIY<\/a><\/span> <span style=\"font-weight: 400;\">\u0e14\u0e39\u0e41\u0e25\u0e40\u0e17\u0e04\u0e41\u0e04\u0e23\u0e4c\u0e01\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e46 \u0e01\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e1a\u0e32\u0e14\u0e41\u0e1c\u0e25\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e25\u0e36\u0e01\u0e40\u0e01\u0e34\u0e19\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e0a\u0e48\u0e32\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49 Frank \u0e21\u0e32\u0e16\u0e36\u0e07\u0e0a\u0e48\u0e27\u0e07\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21<\/span><a href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%A0%E0%B8%B1%E0%B8%A2%E0%B8%A3%E0%B8%96%E0%B8%A2%E0%B8%99%E0%B8%95%E0%B9%8C\/%E0%B9%80%E0%B8%84%E0%B8%A5%E0%B9%87%E0%B8%94%E0%B8%A5%E0%B8%B1%E0%B8%9A\" target=\"_blank\" rel=\"noopener\"><b><span style=\"color: #0000ff;\">\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c<\/span><\/b><\/a> <span style=\"font-weight: 400;\">\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32 <\/span><span style=\"color: #008000;\"><b><i>\u201c \u0e2b\u0e32\u0e01\u0e23\u0e16\u0e40\u0e01\u0e34\u0e14\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e15\u0e23\u0e07\u0e19\u0e35\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e08\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48? \u201d<\/i><\/b><\/span><\/p>\n<p><a href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%A0%E0%B8%B1%E0%B8%A2%E0%B8%A3%E0%B8%96%E0%B8%A2%E0%B8%99%E0%B8%95%E0%B9%8C\/%E0%B9%81%E0%B8%88%E0%B9%89%E0%B8%87%E0%B9%80%E0%B8%84%E0%B8%A5%E0%B8%A1\" target=\"_blank\" rel=\"noopener\"><b><span style=\"color: #0000ff;\">\u0e01\u0e32\u0e23\u0e41\u0e08\u0e49\u0e07\u0e40\u0e04\u0e25\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c<\/span><\/b><\/a> <span style=\"font-weight: 400;\">\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e04\u0e19\u0e43\u0e0a\u0e49\u0e23\u0e16\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e39\u0e49\u0e44\u0e27\u0e49\u0e01\u0e48\u0e2d\u0e19\u0e44\u0e21\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e23\u0e13\u0e35\u0e17\u0e35\u0e48\u0e23\u0e16\u0e40\u0e01\u0e34\u0e14\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e0a\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2d\u0e37\u0e48\u0e19\u0e17\u0e35\u0e48\u0e21\u0e34\u0e43\u0e0a\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e19\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e41\u0e15\u0e48\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e41\u0e08\u0e49\u0e07\u0e40\u0e04\u0e25\u0e21\u0e44\u0e27\u0e49\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e42\u0e14\u0e19\u0e0a\u0e19\u0e15\u0e2d\u0e19\u0e44\u0e2b\u0e19 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e42\u0e14\u0e19\u0e0a\u0e19\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e17\u0e23\u0e32\u0e1a\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e08\u0e39\u0e48\u0e46 \u0e01\u0e47\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32<\/span><span style=\"font-weight: 400;\"> \u0e40\u0e0a\u0e48\u0e19<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"color: #ff6600;\"><strong>\u0e01\u0e49\u0e2d\u0e19\u0e2b\u0e34\u0e19\u0e01\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e43\u0e2a\u0e48\u0e23\u0e16 \u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e34\u0e14\u0e23\u0e2d\u0e22\u0e25\u0e36\u0e01\u00a0<\/strong><\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"color: #ff6600;\"><strong>\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e42\u0e14\u0e19\u0e01\u0e25\u0e31\u0e48\u0e19\u0e41\u0e01\u0e25\u0e49\u0e07 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e31\u0e1a\u0e44\u0e1b\u0e02\u0e39\u0e14\u0e01\u0e31\u0e1a\u0e1f\u0e38\u0e15\u0e1b\u0e32\u0e18 \u0e40\u0e2a\u0e32\u0e44\u0e1f\u0e1f\u0e49\u0e32 \u0e2f\u0e25\u0e2f<\/strong><\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"color: #ff6600;\"><strong>\u0e01\u0e34\u0e48\u0e07\u0e44\u0e21\u0e49\u0e02\u0e39\u0e14\u0e2a\u0e35\u0e23\u0e16 \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e34\u0e48\u0e07\u0e44\u0e21\u0e49\u0e2b\u0e25\u0e48\u0e19\u0e43\u0e2a\u0e48\u0e23\u0e16\u0e15\u0e2d\u0e19\u0e25\u0e21\u0e1e\u0e32\u0e22\u0e38\u0e1e\u0e31\u0e14\u0e41\u0e23\u0e07\u0e46<\/strong><\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"color: #ff6600;\"><strong>\u0e02\u0e31\u0e1a\u0e15\u0e32\u0e21\u0e23\u0e16\u0e1a\u0e23\u0e23\u0e17\u0e38\u0e01\u0e41\u0e25\u0e49\u0e27\u0e02\u0e2d\u0e07\u0e23\u0e48\u0e27\u0e07\u0e2b\u0e25\u0e48\u0e19\u0e43\u0e2a\u0e48\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/strong><\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e04\u0e39\u0e48\u0e01\u0e23\u0e13\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e39\u0e48\u0e01\u0e23\u0e13\u0e35 \u0e41\u0e15\u0e48\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e27\u0e25\u0e32\u0e25\u0e48\u0e27\u0e07\u0e40\u0e25\u0e22\u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 <\/span><span style=\"font-weight: 400;\">\u0e42\u0e14\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e41\u0e08\u0e49\u0e07\u0e40\u0e04\u0e25\u0e21\u0e23\u0e2d\u0e22\u0e19\u0e31\u0e49\u0e19\u0e44\u0e27\u0e49<\/span><span style=\"font-weight: 400;\"> <strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%A0%E0%B8%B1%E0%B8%A2%E0%B8%A3%E0%B8%96%E0%B8%A2%E0%B8%99%E0%B8%95%E0%B9%8C\/%E0%B8%8A%E0%B8%B1%E0%B9%89%E0%B8%991\" target=\"_blank\" rel=\"noopener\">\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e0a\u0e31\u0e49\u0e19 1<\/a> <\/span><\/strong>\u0e01\u0e31\u0e1a\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48 ?<\/span><\/p>\n<p><img class=\"aligncenter size-full wp-image-29221\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e25\u0e37\u0e21\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e44\u0e2b\u0e21-blog.png\" alt=\"\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\" width=\"870\" height=\"540\" srcset=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e25\u0e37\u0e21\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e44\u0e2b\u0e21-blog.png 870w, https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e25\u0e37\u0e21\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e44\u0e2b\u0e21-blog-300x186.png 300w, https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e25\u0e37\u0e21\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e44\u0e2b\u0e21-blog-768x477.png 768w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><\/p>\n<h2><span style=\"color: #008000;\"><b>\u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e43\u0e04\u0e23 ? \u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e19\u0e35\u0e49<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e25\u0e37\u0e21<\/span><span style=\"font-weight: 400;\">\u0e41\u0e08\u0e49\u0e07<\/span><span style=\"font-weight: 400;\">\u0e40\u0e04\u0e25\u0e21\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48 ? \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e44\u0e2b\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e19\u0e35\u0e49\u00a0<\/span><br \/>\n<span style=\"color: #ff6600;\"><b><i>\u201c<\/i><\/b><b><i>\u0e2b\u0e32\u0e01\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e41\u0e08\u0e49\u0e07\u0e40\u0e04\u0e25\u0e21\u0e23\u0e2d\u0e22\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 \u0e41\u0e25\u0e30<\/i><\/b><b><i>\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e27\u0e25\u0e32\u0e25\u0e48\u0e27\u0e07\u0e40\u0e25\u0e22\u0e44\u0e1b\u0e08\u0e19\u0e01\u0e23\u0e30\u0e17\u0e31\u0e48\u0e07\u0e2b\u0e21\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2d\u0e2d\u0e01\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e16\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48\u201d<\/i><\/b><\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e31\u0e49\u0e19 1 \u0e21\u0e35\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e21\u0e32\u0e15\u0e23\u0e27\u0e08\u0e2a\u0e2d\u0e1a\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e01\u0e48\u0e2d\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e02\u0e2d\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e20\u0e32\u0e1e\u0e16\u0e48\u0e32\u0e22\u0e15\u0e23\u0e27\u0e08\u0e40\u0e0a\u0e47\u0e01\u0e2a\u0e20\u0e32\u0e1e\u0e23\u0e16\u0e01\u0e48\u0e2d\u0e19<\/span> <span style=\"font-weight: 400;\">\u0e42\u0e14\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e08\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e1a\u0e1a\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e2b\u0e32\u0e01\u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e25\u0e36\u0e01\u0e01\u0e48\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e01\u0e47\u0e08\u0e30\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e44\u0e27\u0e49<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e42\u0e14\u0e22\u0e40\u0e23\u0e32\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e08\u0e49\u0e07\u0e40\u0e04\u0e25\u0e21\u0e23\u0e2d\u0e22\u0e40\u0e14\u0e34\u0e21\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e01\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e2d\u0e32\u0e22\u0e38\u0e01\u0e23\u0e21\u0e18\u0e23\u0e23\u0e21\u0e4c\u0e09\u0e1a\u0e31\u0e1a\u0e43\u0e2b\u0e21\u0e48 <\/span><span style=\"color: #0000ff;\"><strong>\u0e40\u0e27\u0e49\u0e19\u0e41\u0e15\u0e48\u0e27\u0e48\u0e32\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e1a\u0e31\u0e07\u0e40\u0e2d\u0e34\u0e0d\u0e44\u0e1b\u0e0b\u0e49\u0e33\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e22\u0e40\u0e14\u0e34\u0e21 \u0e15\u0e23\u0e07\u0e19\u0e35\u0e49\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e41\u0e2b\u0e48\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e08\u0e30\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e19\u0e30\u0e04\u0e23\u0e31<\/strong><\/span><span style=\"font-weight: 400;\"><span style=\"color: #0000ff;\"><strong>\u0e1a<\/strong><\/span> \u0e41\u0e15\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e2d\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e48\u0e27\u0e21\u0e08\u0e48\u0e32\u0e22\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22<\/span><\/p>\n<p><img class=\"aligncenter size-full wp-image-29222\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e16\u0e2b\u0e21\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19.jpg\" alt=\"\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\" width=\"870\" height=\"540\" srcset=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e16\u0e2b\u0e21\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19.jpg 870w, https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e16\u0e2b\u0e21\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19-300x186.jpg 300w, https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e23\u0e16\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e43\u0e2b\u0e49\u0e23\u0e16\u0e2b\u0e21\u0e14\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19-768x477.jpg 768w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><\/p>\n<blockquote><p><span style=\"color: #ff6600;\"><b><i>\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e2a\u0e07\u0e2a\u0e31\u0e22\u0e27\u0e48\u0e32 \u0e2d\u0e30\u0e44\u0e23\u0e01\u0e31\u0e19\u0e40\u0e19\u0e35\u0e48\u0e22? \u0e44\u0e2b\u0e19\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e31\u0e49\u0e19 1 \u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e01\u0e23\u0e13\u0e35\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e2b\u0e23\u0e37\u0e2d ? \u0e04\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32 \u0e43\u0e08\u0e40\u0e22\u0e47\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e19\u0e30\u0e40\u0e23\u0e32\u0e02\u0e2d\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49\u00a0<\/i><\/b><\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">\u0e16\u0e36\u0e07\u0e41\u0e21\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e31\u0e49\u0e19 1 \u0e08\u0e30\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e41\u0e15\u0e48\u0e01\u0e47\u0e44\u0e21\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e23\u0e31\u0e1a\u0e1c\u0e21 \u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e22\u0e31\u0e07\u0e21\u0e35<\/span><strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%A3%E0%B8%96%E0%B8%A2%E0%B8%99%E0%B8%95%E0%B9%8C\/%E0%B9%80%E0%B8%84%E0%B8%A5%E0%B9%87%E0%B8%94%E0%B8%A5%E0%B8%B1%E0%B8%9A\/10%E0%B8%84%E0%B8%A7%E0%B8%B2%E0%B8%A1%E0%B9%80%E0%B8%82%E0%B9%89%E0%B8%B2%E0%B9%83%E0%B8%88%E0%B8%9C%E0%B8%B4%E0%B8%94%E0%B9%80%E0%B8%81%E0%B8%B5%E0%B9%88%E0%B8%A2%E0%B8%A7%E0%B8%81%E0%B8%B1%E0%B8%9A%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%A3%E0%B8%96%E0%B8%A2%E0%B8%99%E0%B8%95%E0%B9%8C%E0%B8%8A%E0%B8%B1%E0%B9%89%E0%B8%991\" target=\"_blank\" rel=\"noopener\">\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e1c\u0e34\u0e14\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e0a\u0e31\u0e49\u0e19 1<\/a><\/span><\/strong><span style=\"font-weight: 400;\"> \u0e40\u0e0a\u0e48\u0e19\u00a0<\/span><span style=\"font-weight: 400;\">\u0e44\u0e21\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e2b\u0e32\u0e01\u0e40\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e02\u0e31\u0e1a, \u0e44\u0e21\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e2b\u0e32\u0e01\u0e43\u0e0a\u0e49\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19, \u0e02\u0e31\u0e1a\u0e40\u0e23\u0e47\u0e27\u0e40\u0e01\u0e34\u0e19\u0e08\u0e19\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e41\u0e25\u0e30\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e25\u0e32\u0e01\u0e08\u0e39\u0e07\u0e01\u0e31\u0e1a\u0e23\u0e16\u0e04\u0e31\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e08\u0e19\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22 \u0e2f\u0e25\u0e2f\u00a0<\/span><span style=\"font-weight: 400;\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e2b\u0e32\u0e01\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e04\u0e38\u0e13\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e04\u0e25\u0e21\u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e23\u0e21\u0e18\u0e23\u0e23\u0e21\u0e4c\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e15\u0e01\u0e25\u0e07\u0e44\u0e27\u0e49\u00a0<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">\u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e01\u0e30\u0e17\u0e39\u0e49\u0e02\u0e48\u0e32\u0e27\u0e2e\u0e34\u0e15\u0e08\u0e32\u0e01 Pantip \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07<span style=\"color: #ff0000;\"><strong>\u00a0<\/strong><\/span><\/span><span style=\"color: #008080;\"><strong><a style=\"color: #008080;\" href=\"https:\/\/pantip.com\/topic\/39007591\" target=\"_blank\" rel=\"noopener\">\u0e23\u0e30\u0e27\u0e31\u0e07 \u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 1 \u0e40\u0e27\u0e25\u0e32\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38 \u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e2d\u0e07 50 %<\/a><\/strong><\/span><span style=\"font-weight: 400;\">\u00a0\u0e21\u0e35\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e04\u0e23\u0e48\u0e32\u0e27 \u0e46 \u0e27\u0e48\u0e32<\/span><\/h3>\n<div id=\"attachment_7183\" style=\"width: 1099px\" class=\"wp-caption alignnone\"><a href=\"https:\/\/pantip.com\/topic\/39007591\"><img aria-describedby=\"caption-attachment-7183\" class=\"size-full wp-image-7183\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/pantip.jpg\" alt=\"\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\" width=\"1089\" height=\"785\" \/><\/a><p id=\"caption-attachment-7183\" class=\"wp-caption-text\"><em>\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e08\u0e32\u0e01 pantip \u0e01\u0e23\u0e30\u0e17\u0e39\u0e49\u0e02\u0e48\u0e32\u0e27\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02 39007591<\/em><\/p><\/div>\n<p><i><span style=\"font-weight: 400;\">\u201c\u0e2a\u0e32\u0e40\u0e2b\u0e15\u0e38\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e0a\u0e33\u0e23\u0e30 50% \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2d\u0e49\u0e32\u0e07\u0e27\u0e48\u0e32\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e15\u0e2d\u0e19\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e35\u0e14\u0e02\u0e48\u0e27\u0e19\u0e08\u0e32\u0e01\u0e1e\u0e27\u0e01\u0e43\u0e1a\u0e44\u0e21\u0e49\u0e43\u0e1a\u0e2b\u0e0d\u0e49\u0e32\u0e02\u0e49\u0e32\u0e07\u0e17\u0e32\u0e07\u0e23\u0e2d\u0e1a\u0e04\u0e31\u0e19 \u0e15\u0e2d\u0e19\u0e21\u0e32\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e1c\u0e21\u0e01\u0e47\u0e43\u0e2b\u0e49\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b \u0e40\u0e04\u0e49\u0e32\u0e1a\u0e2d\u0e01\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e1c\u0e21\u0e01\u0e47\u0e1a\u0e2d\u0e01 \u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e01\u0e15\u0e34 \u0e23\u0e16\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e02\u0e31\u0e14\u0e01\u0e47\u0e2b\u0e32\u0e22 \u0e04\u0e19\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e01\u0e47\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b\u0e44\u0e1b \u0e41\u0e25\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e27\u0e48\u0e32\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19 \u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e44\u0e1b \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e40\u0e0b\u0e47\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e32\u0e1a (\u0e1c\u0e21\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e2d\u0e22\u0e1b\u0e01\u0e15\u0e34 \u0e02\u0e31\u0e14\u0e01\u0e47\u0e2b\u0e32\u0e22 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e2d\u0e30\u0e44\u0e23\u0e21\u0e32\u0e01 \u0e41\u0e25\u0e49\u0e27\u0e01\u0e47\u0e40\u0e0b\u0e47\u0e19\u0e25\u0e07\u0e0a\u0e37\u0e48\u0e2d\u0e1c\u0e39\u0e49\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e44\u0e1b\u0e04\u0e23\u0e31\u0e1a)<\/span><\/i><br \/>\n<i><span style=\"font-weight: 400;\">\u0e14\u0e49\u0e27\u0e22\u0e27\u0e48\u0e32 \u0e02\u0e31\u0e1a\u0e23\u0e16\u0e21\u0e32 \u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e40\u0e04\u0e25\u0e21\u0e08\u0e32\u0e01\u0e01\u0e23\u0e13\u0e35\u0e40\u0e23\u0e32\u0e1c\u0e34\u0e14\u0e40\u0e25\u0e22\u0e40\u0e1b\u0e47\u0e19 10 \u0e1b\u0e35\u0e25\u0e30 \u0e41\u0e25\u0e30\u0e23\u0e16\u0e17\u0e38\u0e01\u0e04\u0e31\u0e19\u0e17\u0e35\u0e48\u0e02\u0e31\u0e1a \u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e23\u0e16\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e43\u0e0a\u0e49 \u0e01\u0e47\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e0a\u0e31\u0e49\u0e19 1 \u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e01\u0e47\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e04\u0e34\u0e14\u0e2d\u0e30\u0e44\u0e23 \u0e08\u0e19\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e2a\u0e31\u0e1b\u0e14\u0e32\u0e2b\u0e4c\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e02\u0e31\u0e1a\u0e44\u0e1b\u0e0a\u0e19\u0e23\u0e16\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e08\u0e2d\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e02\u0e49\u0e32\u0e07\u0e17\u0e32\u0e07 (\u0e2d\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e44\u0e1b\u0e0a\u0e19\u0e40\u0e04\u0e49\u0e32\u0e08\u0e23\u0e34\u0e07 \u0e46 \u0e1c\u0e34\u0e14\u0e04\u0e23\u0e31\u0e49\u0e07\u0e41\u0e23\u0e01\u0e40\u0e25\u0e22) \u0e01\u0e47\u0e40\u0e23\u0e35\u0e22\u0e01\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e47\u0e40\u0e2d\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e0b\u0e48\u0e2d\u0e21 \u0e1b\u0e01\u0e15\u0e34 \u0e08\u0e39\u0e48 \u0e46 \u0e17\u0e32\u0e07\u0e28\u0e38\u0e19\u0e22\u0e4c \u0e42\u0e17\u0e23\u0e21\u0e32\u0e41\u0e08\u0e49\u0e07\u0e27\u0e48\u0e32 \u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e2d\u0e2d\u0e01\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e2d\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e08\u0e33\u0e19\u0e27\u0e19 50% \u0e02\u0e2d\u0e07\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e07\u0e07<\/span><\/i><br \/>\n<i><span style=\"font-weight: 400;\">\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e2d\u0e49\u0e32\u0e07\u0e27\u0e48\u0e32 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e15\u0e48\u0e01\u0e48\u0e2d\u0e19 \u0e08\u0e36\u0e07\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32 \u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19 \u0e17\u0e32\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e2d\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e08\u0e36\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e40\u0e07\u0e34\u0e19\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e40\u0e2d\u0e07 50% \u0e41\u0e15\u0e48\u0e17\u0e32\u0e07\u0e1c\u0e21\u0e44\u0e21\u0e48\u0e22\u0e2d\u0e21\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19 \u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e21\u0e31\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e27\u0e01\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e02\u0e31\u0e14\u0e2b\u0e32\u0e22\u0e44\u0e14\u0e49 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e15\u0e01\u0e2b\u0e31\u0e01 \u0e1a\u0e38\u0e1a\u0e1a\u0e34\u0e48\u0e19 \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e23\u0e34\u0e07 \u0e46 \u0e41\u0e25\u0e49\u0e27 \u0e1c\u0e21\u0e01\u0e47\u0e40\u0e2d\u0e32\u0e23\u0e16\u0e44\u0e1b\u0e02\u0e31\u0e14\u0e2a\u0e35\u0e21\u0e32\u0e01\u0e48\u0e2d\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e19\u0e35\u0e49\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e41\u0e25\u0e30\u0e23\u0e2d\u0e22\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e01\u0e47\u0e2b\u0e32\u0e22\u0e2b\u0e21\u0e14\u0e41\u0e25\u0e49\u0e27\u0e04\u0e23\u0e31\u0e1a \u0e41\u0e15\u0e48\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e1a\u0e2d\u0e01\u0e27\u0e48\u0e32 \u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e17\u0e33\u0e41\u0e25\u0e49\u0e27 \u0e15\u0e49\u0e2d\u0e07\u0e41\u0e08\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e17\u0e32\u0e07\u0e40\u0e04\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b update \u0e44\u0e27\u0e49\u0e14\u0e49\u0e27\u0e22 (\u0e40\u0e2d \u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e44\u0e14\u0e49\u0e22\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e17\u0e33\u0e08\u0e23\u0e34\u0e07 \u0e46 \u0e04\u0e23\u0e31\u0e1a\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49)\u201d<\/span><\/i><span style=\"font-weight: 400;\"> \u0e02\u0e2d\u0e2d\u0e19\u0e38\u0e0d\u0e32\u0e15\u0e2d\u0e49\u0e32\u0e07\u0e2d\u0e34\u0e07\u0e08\u0e32\u0e01\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e23\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e2a\u0e21\u0e32\u0e0a\u0e34\u0e01 coolearth \u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\u0e01\u0e23\u0e30\u0e17\u0e39\u0e49 39007591<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e49\u0e33\u0e27\u0e48\u0e32 <span style=\"color: #0000ff;\"><strong>\u201c<\/strong><\/span><\/span><span style=\"color: #0000ff;\"><strong><i>\u0e16\u0e49\u0e32\u0e40\u0e23\u0e32\u0e17\u0e33\u0e41\u0e25\u0e49\u0e27 \u0e15\u0e49\u0e2d\u0e07\u0e41\u0e08\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e17\u0e32\u0e07\u0e40\u0e04\u0e49\u0e32\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e16\u0e48\u0e32\u0e22\u0e23\u0e39\u0e1b Update \u0e44\u0e27\u0e49\u0e14\u0e49\u0e27\u0e22 <\/i><\/strong><\/span><span style=\"font-weight: 400;\"><span style=\"color: #0000ff;\"><strong>\u201d<\/strong><\/span> \u0e2b\u0e21\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e40\u0e23\u0e32\u0e40\u0e0b\u0e47\u0e19\u0e23\u0e31\u0e1a\u0e17\u0e23\u0e32\u0e1a\u0e27\u0e48\u0e32\u0e23\u0e16\u0e40\u0e23\u0e32\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19 \u0e2b\u0e32\u0e01\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e17\u0e33\u0e01\u0e32\u0e23\u0e0b\u0e48\u0e2d\u0e21\u0e41\u0e0b\u0e21\u0e23\u0e16\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e08\u0e49\u0e07\u0e43\u0e2b\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e17\u0e23\u0e32\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e49\u0e32\u0e44\u0e21\u0e48\u0e41\u0e08\u0e49\u0e07 \u0e41\u0e25\u0e30\u0e14\u0e31\u0e19\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e42\u0e14\u0e22\u0e40\u0e23\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19 \u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e2f \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u00a0<\/span><\/p>\n<h2><span style=\"color: #008000;\"><b>\u0e41\u0e25\u0e49\u0e27\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e40\u0e23\u0e32\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e44\u0e2b\u0e21\u0e25\u0e48\u0e30 ?<\/b><\/span><\/h2>\n<p><img class=\"aligncenter size-full wp-image-29226\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e48\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38.jpg\" alt=\"\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38\" width=\"870\" height=\"540\" srcset=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e48\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38.jpg 870w, https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e48\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38-300x186.jpg 300w, https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e01\u0e48\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38-768x477.jpg 768w\" sizes=\"(max-width: 870px) 100vw, 870px\" \/><\/p>\n<h2><span style=\"color: #008000;\"><b>\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e22\u0e01\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e40\u0e1b\u0e47\u0e19 2 \u0e01\u0e23\u0e13\u0e35<\/b><\/span><\/h2>\n<ol>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e23\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e09\u0e1a\u0e31\u0e1a\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e2d\u0e31\u0e19\u0e19\u0e35\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e2d\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e48\u0e27\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e23\u0e31\u0e1a<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e23\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e2b\u0e25\u0e31\u0e07\u0e17\u0e33\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e09\u0e1a\u0e31\u0e1a\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e01\u0e23\u0e13\u0e35\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e48\u0e27\u0e21\u0e08\u0e48\u0e32\u0e22\u0e04\u0e48\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e23\u0e01 \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e48\u0e32\u0e40\u0e2d\u0e47\u0e01\u0e40\u0e0b\u0e2a (Excess) \u0e42\u0e14\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e08\u0e30\u0e40\u0e23\u0e35\u0e22\u0e01\u0e40\u0e01\u0e47\u0e1a\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e2d\u0e32\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e38\u0e1a\u0e31\u0e15\u0e34\u0e40\u0e2b\u0e15\u0e38\u0e02\u0e36\u0e49\u0e19 \u0e15\u0e32\u0e21\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e02\u0e2d\u0e07<\/span><a href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%A0%E0%B8%B1%E0%B8%A2%E0%B8%A3%E0%B8%96%E0%B8%A2%E0%B8%99%E0%B8%95%E0%B9%8C\/%E0%B9%80%E0%B8%84%E0%B8%A5%E0%B9%87%E0%B8%94%E0%B8%A5%E0%B8%B1%E0%B8%9A\/%E0%B9%80%E0%B8%84%E0%B8%A5%E0%B8%A1%E0%B8%A3%E0%B8%AD%E0%B8%9A%E0%B8%84%E0%B8%B1%E0%B8%99%E0%B8%95%E0%B9%89%E0%B8%AD%E0%B8%87%E0%B8%88%E0%B9%88%E0%B8%B2%E0%B8%A2-%E0%B8%84%E0%B9%88%E0%B8%B2excess%E0%B9%84%E0%B8%AB%E0%B8%A1\" target=\"_blank\" rel=\"noopener\"><b><span style=\"color: #ff6600;\">\u0e04\u0e48\u0e32\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e23\u0e01 (Excess)<\/span><\/b><\/a> <span style=\"font-weight: 400;\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e41\u0e08\u0e49\u0e07\u0e40\u0e04\u0e25\u0e21\u0e41\u0e1a\u0e1a\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e39\u0e48\u0e01\u0e23\u0e13\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e04\u0e39\u0e48\u0e01\u0e23\u0e13\u0e35\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e04\u0e23 \u0e14\u0e49\u0e27\u0e22\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e08\u0e32\u0e01\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e17\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e23\u0e16 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e01\u0e34\u0e14\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e0a\u0e19\u0e01\u0e31\u0e1a\u0e23\u0e16 \u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e30\u0e1a\u0e38\u0e04\u0e39\u0e48\u0e01\u0e23\u0e13\u0e35\u0e44\u0e14\u0e49\u0e43\u0e19\u0e0b\u0e36\u0e48\u0e07\u0e17\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e27\u0e32\u0e21\u0e44\u0e21\u0e48\u0e23\u0e30\u0e21\u0e31\u0e14\u0e23\u0e30\u0e27\u0e31\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e25\u0e48\u0e30\u0e04\u0e23\u0e31\u0e1a\u00a0<\/span><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e01\u0e48\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e08\u0e30\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e43\u0e2b\u0e49\u0e2a\u0e33\u0e23\u0e27\u0e08\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e23\u0e16\u0e40\u0e23\u0e32\u0e27\u0e48\u0e32\u0e21\u0e35\u0e23\u0e48\u0e2d\u0e07\u0e23\u0e2d\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e08\u0e38\u0e14\u0e43\u0e14\u0e1a\u0e49\u0e32\u0e07 \u0e41\u0e25\u0e30\u0e43\u0e2b\u0e49\u0e23\u0e35\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e40\u0e04\u0e25\u0e21\u0e01\u0e48\u0e2d\u0e19\u0e2a\u0e34\u0e49\u0e19\u0e2a\u0e38\u0e14\u0e2d\u0e32\u0e22\u0e38\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e14\u0e34\u0e21 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e43\u0e1a\u0e40\u0e04\u0e25\u0e21\u0e43\u0e2b\u0e49 \u0e42\u0e14\u0e22\u0e43\u0e1a\u0e40\u0e04\u0e25\u0e21\u0e08\u0e30\u0e21\u0e35\u0e2d\u0e32\u0e22\u0e38\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 6 \u0e40\u0e14\u0e37\u0e2d\u0e19\u0e16\u0e36\u0e07 1 \u0e1b\u0e35 \u0e19\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e41\u0e08\u0e49\u0e07\u0e40\u0e04\u0e25\u0e21 \u0e17\u0e35\u0e48\u0e19\u0e35\u0e49\u0e16\u0e49\u0e32\u0e04\u0e38\u0e13\u0e41\u0e08\u0e49\u0e07\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e19\u0e1a\u0e43\u0e1a\u0e40\u0e04\u0e25\u0e21\u0e19\u0e35\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e15\u0e23\u0e27\u0e08\u0e23\u0e16\u0e44\u0e14\u0e49 \u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e41\u0e08\u0e49\u0e07\u0e40\u0e04\u0e25\u0e21\u0e17\u0e35\u0e48\u0e40\u0e14\u0e34\u0e21\u0e41\u0e25\u0e49\u0e27\u0e19\u0e30 \u0e41\u0e25\u0e49\u0e27\u0e16\u0e49\u0e32\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e0b\u0e49\u0e33\u0e23\u0e2d\u0e22\u0e40\u0e14\u0e34\u0e21\u0e42\u0e14\u0e22\u0e17\u0e35\u0e48\u0e43\u0e1a\u0e40\u0e04\u0e25\u0e21\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e01\u0e47\u0e08\u0e30\u0e08\u0e48\u0e32\u0e22\u0e04\u0e48\u0e32\u0e0b\u0e48\u0e2d\u0e21\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e14\u0e34\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u0e40\u0e2d\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e48\u0e32<\/span><span style=\"color: #008080;\"><b> \u201c\u0e02\u0e31\u0e1a\u0e02\u0e35\u0e48\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e21\u0e35\u0e2a\u0e15\u0e34\u0e17\u0e38\u0e01\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e08\u0e30\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u201d<\/b><\/span><span style=\"font-weight: 400;\"> \u0e2b\u0e32\u0e01\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e01\u0e47\u0e23\u0e35\u0e1a\u0e41\u0e08\u0e49\u0e07\u0e17\u0e31\u0e19\u0e17\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e02\u0e2d\u0e43\u0e1a\u0e40\u0e04\u0e25\u0e21\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2d\u0e22\u0e48\u0e32\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e40\u0e27\u0e25\u0e32\u0e43\u0e2b\u0e49\u0e25\u0e48\u0e27\u0e07\u0e40\u0e25\u0e22\u0e08\u0e30\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e19\u0e30\u0e08\u0e49\u0e30<\/span><\/p>\n<p><b>\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13 :<\/b> <a href=\"https:\/\/pantip.com\/topic\/39007591\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">pantip.com<\/span><\/a><br \/>\nContent by Butter Cutter<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e44\u0e21\u0e48\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e43\u0e0a\u0e49 \u0e27\u0e34\u0e18\u0e35\u0e25\u0e1a\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e1a\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e41\u0e1a\u0e1a DIY \u0e14\u0e39\u0e41\u0e25\u0e40\u0e17\u0e04\u0e41\u0e04\u0e23\u0e4c\u0e01\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e1a\u0e49\u0e32\u0e19 \u0e46 \u0e01\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e1a\u0e32\u0e14\u0e41\u0e1c\u0e25\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e25\u0e36\u0e01\u0e40\u0e01\u0e34\u0e19\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e2b\u0e49\u0e0a\u0e48\u0e32\u0e07\u0e0b\u0e48\u0e2d\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49 Frank \u0e21\u0e32\u0e16\u0e36\u0e07\u0e0a\u0e48\u0e27\u0e07\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e19\u0e48\u0e32\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19\u0e15\u0e4c \u0e01\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32 \u201c \u0e2b\u0e32\u0e01\u0e23\u0e16\u0e40\u0e01\u0e34\u0e14\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e02\u0e35\u0e14\u0e17\u0e35\u0e48\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e22\u0e19<\/p>\n","protected":false},"author":20,"featured_media":29224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[2059,2063],"tags":[1128,1119,1649,1055,1098,1035,1638,1676,1650,1651,1639],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.0 (Yoast SEO v20.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 ??<\/title>\n<meta name=\"description\" content=\"\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e21\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2d\u0e22\u0e48\u0e32\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bolttech.co.th\/blog\/\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\" \/>\n<meta property=\"og:description\" content=\"\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e21\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2d\u0e22\u0e48\u0e32\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bolttech.co.th\/blog\/\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\" \/>\n<meta property=\"og:site_name\" content=\"Bolttech Blog - News &amp; Updates\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-22T00:19:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-10T10:21:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/FB-cover-\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14-\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19-1-\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48.jpg\" \/>\n<meta name=\"author\" content=\"Butter Cutter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@bolttechTH\" \/>\n<meta name=\"twitter:site\" content=\"@bolttechTH\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Butter Cutter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99\",\"url\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99\",\"name\":\"\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 ??\",\"isPartOf\":{\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#website\"},\"datePublished\":\"2019-07-22T00:19:51+00:00\",\"dateModified\":\"2023-08-10T10:21:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9\"},\"description\":\"\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e21\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2d\u0e22\u0e48\u0e32\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bolttech.co.th\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#website\",\"url\":\"https:\/\/www.bolttech.co.th\/blog\/\",\"name\":\"Bolttech Blog - News &amp; Updates\",\"description\":\"Bolttech Blog - News &amp; Updates\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bolttech.co.th\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9\",\"name\":\"Butter Cutter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g\",\"caption\":\"Butter Cutter\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 ??","description":"\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e21\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2d\u0e22\u0e48\u0e32\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bolttech.co.th\/blog\/\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19","og_locale":"th_TH","og_type":"article","og_title":"\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48","og_description":"\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e21\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2d\u0e22\u0e48\u0e32\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21","og_url":"https:\/\/www.bolttech.co.th\/blog\/\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19","og_site_name":"Bolttech Blog - News &amp; Updates","article_published_time":"2019-07-22T00:19:51+00:00","article_modified_time":"2023-08-10T10:21:28+00:00","og_image":[{"url":"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/07\/FB-cover-\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14-\u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19-1-\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48.jpg"}],"author":"Butter Cutter","twitter_card":"summary_large_image","twitter_creator":"@bolttechTH","twitter_site":"@bolttechTH","twitter_misc":{"Written by":"Butter Cutter","Est. reading time":"3 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99","url":"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99","name":"\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48 ??","isPartOf":{"@id":"https:\/\/www.bolttech.co.th\/blog\/#website"},"datePublished":"2019-07-22T00:19:51+00:00","dateModified":"2023-08-10T10:21:28+00:00","author":{"@id":"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9"},"description":"\u0e15\u0e2d\u0e1a\u0e04\u0e33\u0e16\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e20\u0e31\u0e22\u0e23\u0e16 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e25\u0e21\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e2d\u0e22\u0e48\u0e32\u0e17\u0e34\u0e49\u0e07\u0e44\u0e27\u0e49\u0e08\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e14\u0e31\u0e07\u0e19\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e23\u0e40\u0e04\u0e25\u0e21\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e08\u0e32\u0e01\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e2b\u0e21\u0e14\u0e2d\u0e32\u0e22\u0e38 \u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e43\u0e2b\u0e21\u0e48\u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e48\u0e32\u0e22\u0e40\u0e1e\u0e34\u0e48\u0e21","breadcrumb":{"@id":"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%a3%e0%b8%96%e0%b8%a1%e0%b8%b5%e0%b8%a3%e0%b8%ad%e0%b8%a2%e0%b8%81%e0%b9%88%e0%b8%ad%e0%b8%99%e0%b8%95%e0%b9%88%e0%b8%ad%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b8%81%e0%b8%b1%e0%b8%99#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bolttech.co.th\/blog"},{"@type":"ListItem","position":2,"name":"\u0e23\u0e16\u0e21\u0e35\u0e23\u0e2d\u0e22\u0e02\u0e39\u0e14 \u0e01\u0e48\u0e2d\u0e19\u0e15\u0e48\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e16\u0e0a\u0e31\u0e49\u0e19 1 \u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48"}]},{"@type":"WebSite","@id":"https:\/\/www.bolttech.co.th\/blog\/#website","url":"https:\/\/www.bolttech.co.th\/blog\/","name":"Bolttech Blog - News &amp; Updates","description":"Bolttech Blog - News &amp; Updates","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bolttech.co.th\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9","name":"Butter Cutter","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g","caption":"Butter Cutter"}}]}},"_links":{"self":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts\/7177"}],"collection":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/comments?post=7177"}],"version-history":[{"count":4,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts\/7177\/revisions"}],"predecessor-version":[{"id":29228,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts\/7177\/revisions\/29228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/media\/29224"}],"wp:attachment":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/media?parent=7177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/categories?post=7177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/tags?post=7177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}