{"id":8759,"date":"2019-11-10T10:12:55","date_gmt":"2019-11-10T03:12:55","guid":{"rendered":"https:\/\/www.bolttech.co.th\/blog?p=8759"},"modified":"2019-11-10T10:12:55","modified_gmt":"2019-11-10T03:12:55","slug":"%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2","status":"publish","type":"post","link":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2","title":{"rendered":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e21\u0e35\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 6 \u0e1e\u0e34\u0e01\u0e31\u0e14 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e2a\u0e34 ?"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">\u0e2b\u0e32\u0e41\u0e1e\u0e25\u0e19\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e41\u0e25\u0e30\u0e21\u0e35\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22!! \u0e1a\u0e19\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32<\/span><b><i><span style=\"color: #ff6600;\"> \u201c\u0e21\u0e35\u0e07\u0e1a 10,000 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e2b\u0e19\u0e14\u0e35?\u201d<\/span> <\/i><\/b><span style=\"font-weight: 400;\">\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e42\u0e19\u0e2a\u0e19\u0e42\u0e19\u0e41\u0e04\u0e23\u0e4c\u0e27\u0e48\u0e32 \u201c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e17 \u0e1c\u0e39\u0e49\u0e40\u0e17\u0e41\u0e25\u0e49\u0e27\u0e44\u0e07 \u0e40\u0e23\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e47\u0e44\u0e14\u0e49!\u201d \u0e40\u0e1e\u0e19\u0e01\u0e27\u0e34\u0e19\u0e41\u0e1f\u0e23\u0e07\u0e04\u0e4c\u0e21\u0e35 6 \u0e1e\u0e34\u0e01\u0e31\u0e14\u0e43\u0e19 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e04\u0e23\u0e49\u0e32\u0e1a\u0e1a\u0e1a\u00a0<\/span><\/p>\n<h2><span style=\"color: #29579b;\"><b>1. \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e22\u0e48\u0e32\u0e07\u0e01\u0e38\u0e49\u0e07 \u0e1a\u0e38\u0e01\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e21\u0e48\u0e32\u00a0<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e2b\u0e19\u0e14\u0e35\u0e40\u0e1b\u0e47\u0e19<a href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%94%E0%B8%B4%E0%B8%99%E0%B8%97%E0%B8%B2%E0%B8%87\/%E0%B8%88%E0%B8%B8%E0%B8%94%E0%B8%AB%E0%B8%A1%E0%B8%B2%E0%B8%A2%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%94%E0%B8%B4%E0%B8%99%E0%B8%97%E0%B8%B2%E0%B8%87\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B9%80%E0%B8%97%E0%B8%A8%E0%B8%9F%E0%B8%A3%E0%B8%B5%E0%B8%A7%E0%B8%B5%E0%B8%8B%E0%B9%88%E0%B8%B2\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #00d0bc;\"><em><strong>\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1f\u0e23\u0e35\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e04\u0e19\u0e44\u0e17\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e21\u0e35\u0e1e\u0e32\u0e2a\u0e1b\u0e2d\u0e23\u0e4c\u0e15 (Passport)<\/strong> <\/em><\/span><\/a><\/span><span style=\"font-weight: 400;\">\u0e40\u0e08\u0e34\u0e21\u0e14\u0e49\u0e27\u0e22\u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e43\u0e01\u0e25\u0e49\u0e44\u0e17\u0e22\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e21\u0e35\u0e22\u0e19\u0e21\u0e32\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e1e\u0e21\u0e48\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e1a\u0e38\u0e01<span style=\"color: #29579b;\"><strong>\u0e01\u0e23\u0e38\u0e07\u0e22\u0e48\u0e32\u0e07\u0e01\u0e38\u0e49\u0e07 (Yongon)<\/strong> <\/span>\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e07\u0e1a\u0e44\u0e21\u0e48\u0e41\u0e1e\u0e07\u0e44\u0e21\u0e48\u0e1a\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e2b\u0e27\u0e49\u0e1e\u0e23\u0e30\u0e02\u0e2d\u0e1e\u0e23 \u0e40\u0e0a\u0e48\u0e19 \u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c\u0e0a\u0e40\u0e27\u0e14\u0e32\u0e01\u0e2d\u0e07, \u0e1e\u0e23\u0e30\u0e40\u0e08\u0e49\u0e32\u0e15\u0e32\u0e2b\u0e27\u0e32\u0e19 \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e02\u0e2d\u0e1e\u0e23\u0e01\u0e31\u0e1a\u0e40\u0e17\u0e1e\u0e17\u0e31\u0e19\u0e43\u0e08\u0e19\u0e31\u0e15\u0e42\u0e1a\u0e42\u0e1a\u0e22\u0e35 \u0e40\u0e08\u0e14\u0e35\u0e22\u0e4c\u0e42\u0e1a\u0e15\u0e32\u0e17\u0e32\u0e27\u0e19\u0e4c \u0e41\u0e25\u0e30\u0e41\u0e27\u0e30\u0e0a\u0e34\u0e21\u0e01\u0e38\u0e49\u0e07\u0e40\u0e1c\u0e32\u0e2d\u0e23\u0e48\u0e2d\u0e22 \u0e46 \u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e08\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e01\u0e25\u0e31\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e44\u0e1b\u0e19\u0e2d\u0e19\u0e2a\u0e31\u0e01 3 \u0e27\u0e31\u0e19 2 \u0e04\u0e37\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49<\/span><\/p>\n<h3><span style=\"color: #29579b;\"><b>\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13<\/b><\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e44\u0e1b\u0e01\u0e25\u0e31\u0e1a (\u0e01\u0e17\u0e21. - \u0e22\u0e48\u0e32\u0e07\u0e01\u0e38\u0e49\u0e07) \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48 2,XXX \u0e1a\u0e32\u0e17 <\/span><i><span style=\"font-weight: 400;\">(\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32)<\/span><\/i><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 1,XXX \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e37\u0e19 (\u0e1e\u0e31\u0e01 2 \u0e04\u0e37\u0e19\u0e01\u0e47\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2,000 \u0e1a\u0e32\u0e17)<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 2,XXX \u0e1a\u0e32\u0e17 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e1c\u0e37\u0e48\u0e2d\u0e44\u0e27\u0e49<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e44\u0e27\u0e49\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e0a\u0e49\u0e2d\u0e1b \u0e01\u0e34\u0e19 \u0e1f\u0e34\u0e19 \u0e46\u00a0 \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 4,000 \u0e1a\u0e32\u0e17 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e27\u0e30\u0e0a\u0e49\u0e2d\u0e1b\u0e17\u0e35\u0e48\u0e15\u0e25\u0e32\u0e14\u0e2a\u0e01\u0e47\u0e2d\u0e15\u0e2b\u0e23\u0e37\u0e2d Botyoke Aung San Market \u0e04\u0e48\u0e30<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e1e\u0e21\u0e48\u0e32\u0e08\u0e30\u0e21\u0e35\u0e2a\u0e01\u0e38\u0e25\u0e40\u0e07\u0e34\u0e19\u0e08\u0e4a\u0e32\u0e14 (Kyat) \u0e41\u0e25\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e25\u0e37\u0e21\u0e41\u0e25\u0e01\u0e14\u0e2d\u0e25\u0e25\u0e32\u0e23\u0e4c\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e01\u0e47\u0e14\u0e35\u0e19\u0e30\u0e04\u0e30 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e17\u0e35\u0e48\u0e42\u0e19\u0e49\u0e19\u0e19\u0e34\u0e22\u0e21\u0e0a\u0e33\u0e23\u0e30\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e14\u0e49\u0e27\u0e22\u0e40\u0e07\u0e34\u0e19\u0e14\u0e2d\u0e25\u0e25\u0e32\u0e23\u0e4c (USD) \u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e2d\u0e49\u0e2d! \u0e2a\u0e32\u0e27 \u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e2a\u0e33\u0e23\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e19\u0e30\u0e04\u0e30 \u0e07\u0e14\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e42\u0e1b\u0e23\u0e07\u0e2a\u0e31\u0e49\u0e19 \u0e01\u0e32\u0e07\u0e40\u0e01\u0e07\u0e02\u0e32\u0e2a\u0e31\u0e49\u0e19 \u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e40\u0e27\u0e49\u0e32\u0e25\u0e36\u0e01 \u0e2a\u0e32\u0e22\u0e40\u0e14\u0e35\u0e48\u0e22\u0e27 \u0e07\u0e14\u0e01\u0e48\u0e2d\u0e19\u0e19\u0e30\u0e08\u0e49\u0e30<\/span><br \/>\n<img class=\"alignnone size-full wp-image-8766\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-04.jpg\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\" width=\"871\" height=\"540\" \/><\/p>\n<h2><span style=\"color: #29579b;\"><b>2. \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e25\u0e32\u0e27 \u0e1a\u0e38\u0e01\u0e40\u0e27\u0e35\u0e22\u0e07\u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e21\u0e35\u0e07\u0e1a 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e2b\u0e19\u0e14\u0e35 ? \u0e2b\u0e32\u0e01\u0e42\u0e25\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e1e\u0e21\u0e48\u0e32\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e16\u0e39\u0e01\u0e43\u0e08\u0e04\u0e38\u0e13 \u0e25\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2a\u0e1b\u0e1b.\u0e25\u0e32\u0e27\u0e14\u0e39\u0e2a\u0e34\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e19\u0e44\u0e21\u0e48\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e40\u0e19\u0e49\u0e19\u0e44\u0e17\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e07\u0e34\u0e19\u0e44\u0e17\u0e22\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e40\u0e23\u0e32\u0e41\u0e27\u0e30\u0e15\u0e31\u0e01\u0e1a\u0e32\u0e15\u0e23\u0e02\u0e49\u0e32\u0e27\u0e40\u0e2b\u0e19\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e27\u0e35\u0e22\u0e07\u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e2a\u0e27\u0e22\u0e04\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2d\u0e01\u0e25\u0e31\u0e01\u0e29\u0e13\u0e4c \u0e1e\u0e34\u0e01\u0e31\u0e14\u0e19\u0e35\u0e49\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e44\u0e21\u0e48\u0e2a\u0e39\u0e07\u0e21\u0e32\u0e01\u0e04\u0e23\u0e31\u0e1a<span style=\"color: #00d0bc;\"><em><strong> \u0e41\u0e27\u0e30\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e1e\u0e23\u0e30\u0e18\u0e32\u0e15\u0e38\u0e2b\u0e25\u0e27\u0e07 \u0e14\u0e39\u0e1b\u0e23\u0e30\u0e15\u0e39\u0e44\u0e0b<\/strong> <\/em><\/span>\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e27\u0e31\u0e14\u0e2a\u0e35\u0e2a\u0e30\u0e40\u0e01\u0e14\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e40\u0e01\u0e48\u0e32\u0e41\u0e01\u0e48 \u0e15\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e27\u0e31\u0e14\u0e28\u0e23\u0e35\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e2b\u0e27\u0e49\u0e02\u0e2d\u0e42\u0e0a\u0e04\u0e25\u0e32\u0e20\u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e17\u0e2d\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01<\/span><br \/>\n<img class=\"alignnone size-full wp-image-8767\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-05.jpg\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\" width=\"871\" height=\"540\" \/><\/p>\n<h3><span style=\"color: #00d0bc;\"><b>\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13<\/b><\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e44\u0e1b\u0e01\u0e25\u0e31\u0e1a (\u0e01\u0e17\u0e21.-\u0e40\u0e27\u0e35\u0e22\u0e07\u0e08\u0e31\u0e19\u0e17\u0e19\u0e4c) \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48 2,XXX \u0e1a\u0e32\u0e17 <\/span><i><span style=\"font-weight: 400;\">(\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32)<\/span><\/i><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 XXX \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e37\u0e19\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 \u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 2,XXX \u0e1a\u0e32\u0e17 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e40\u0e1c\u0e37\u0e48\u0e2d\u0e44\u0e27\u0e49<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e41\u0e25\u0e30\u0e40\u0e07\u0e34\u0e19\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e04\u0e37\u0e2d\u0e2a\u0e48\u0e27\u0e19\u0e0a\u0e49\u0e2d\u0e1b\u0e1b\u0e34\u0e49\u0e07 \u0e01\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e23\u0e31\u0e1a<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e25\u0e32\u0e27\u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e0a\u0e49\u0e40\u0e07\u0e34\u0e19\u0e44\u0e17\u0e22 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e41\u0e25\u0e01\u0e41\u0e1a\u0e07\u0e04\u0e4c\u0e22\u0e35\u0e48\u0e2a\u0e34\u0e1a\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e04\u0e38\u0e13\u0e08\u0e30\u0e41\u0e25\u0e01\u0e40\u0e07\u0e34\u0e19\u0e14\u0e2d\u0e25\u0e25\u0e32\u0e23\u0e4c \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e07\u0e34\u0e19\u0e01\u0e35\u0e1a\u0e01\u0e47\u0e44\u0e14\u0e49 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e16\u0e49\u0e32\u0e43\u0e0a\u0e49\u0e40\u0e07\u0e34\u0e19\u0e44\u0e17\u0e22\u0e0b\u0e37\u0e49\u0e2d\u0e02\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e07\u0e17\u0e32\u0e07\u0e1a\u0e32\u0e07\u0e04\u0e23\u0e31\u0e49\u0e07\u0e01\u0e47\u0e16\u0e39\u0e01\u0e04\u0e34\u0e14\u0e23\u0e32\u0e04\u0e32\u0e41\u0e1e\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19<\/span><br \/>\n<b>\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21\u0e17\u0e35\u0e48\u0e04\u0e38\u0e13\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e2a\u0e19\u0e43\u0e08 :<\/b> <span style=\"color: #29579b;\"><strong><a style=\"color: #29579b;\" href=\"https:\/\/www.bolttech.co.th\/blog\/10-%e0%b8%9e%e0%b8%b4%e0%b8%81%e0%b8%b1%e0%b8%94%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%a5%e0%b8%b2%e0%b8%a7\">10 \u0e1e\u0e34\u0e01\u0e31\u0e14\u0e17\u0e35\u0e48\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e25\u0e32\u0e27 \u0e40\u0e15\u0e47\u0e21\u0e2d\u0e34\u0e48\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e08\u0e23\u0e14\u0e43\u0e15\u0e49<\/a><\/strong><\/span><\/p>\n<h2><span style=\"color: #29579b;\"><b>3. \u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21 \u0e41\u0e27\u0e30\u0e0b\u0e32\u0e1b\u0e32\u0e01\u0e31\u0e19\u0e14\u0e35\u0e44\u0e2b\u0e21<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e2b\u0e19\u0e14\u0e35\u0e1a\u0e38\u0e01<span style=\"color: #29579b;\"><strong>\u0e0b\u0e32\u0e1b\u0e32 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21<\/strong><\/span> \u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e1a\u0e23\u0e34\u0e2a\u0e38\u0e17\u0e18\u0e34\u0e4c\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e41\u0e2b\u0e48\u0e07\u0e2a\u0e32\u0e22\u0e2b\u0e21\u0e2d\u0e01\u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e40\u0e23\u0e32\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e23\u0e1a\u0e2d\u0e22\u0e39\u0e48\u0e2a\u0e1a\u0e32\u0e22\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e07\u0e1a 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e1a\u0e32\u0e17\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 3 \u0e27\u0e31\u0e19 2 \u0e04\u0e37\u0e19 \u0e07\u0e1a\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e46 \u0e01\u0e25\u0e31\u0e1a\u0e44\u0e17\u0e22\u0e40\u0e25\u0e22\u0e41\u0e2b\u0e25\u0e30 \u0e41\u0e27\u0e30\u0e0a\u0e21\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34\u0e02\u0e2d\u0e07\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e32\u0e22\u0e41\u0e14\u0e19\u0e08\u0e35\u0e19\u0e17\u0e35\u0e48\u0e43\u0e19\u0e2d\u0e14\u0e35\u0e15\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e15\u0e32\u0e01\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e02\u0e2d\u0e07\u0e0a\u0e32\u0e27\u0e1d\u0e23\u0e31\u0e48\u0e07\u0e40\u0e28\u0e2a \u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e40\u0e22\u0e47\u0e19 \u0e46 \u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e1b\u0e35 \u0e40\u0e23\u0e32\u0e08\u0e30\u0e44\u0e14\u0e49\u0e41\u0e27\u0e30\u0e0a\u0e21\u0e44\u0e23\u0e48\u0e19\u0e32\u0e02\u0e31\u0e49\u0e19\u0e1a\u0e31\u0e19\u0e44\u0e14 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e0a\u0e32\u0e27\u0e40\u0e1c\u0e48\u0e32\u0e21\u0e49\u0e07\u0e17\u0e35\u0e48\u0e2b\u0e21\u0e39\u0e48\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e31\u0e15\u0e01\u0e31\u0e15 (Cat Cat Villlage) \u0e41\u0e25\u0e30\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e19\u0e49\u0e33\u0e15\u0e01\u0e0b\u0e34\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e4c (Silver Waterfall) \u0e14\u0e35\u0e15\u0e48\u0e2d\u0e43\u0e08\u0e2a\u0e32\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e1c\u0e39\u0e49\u0e23\u0e31\u0e01\u0e29\u0e4c\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34<\/span><br \/>\n<img class=\"alignnone size-full wp-image-8768\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-06.jpg\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\" width=\"871\" height=\"540\" \/><\/p>\n<h3><span style=\"color: #00d0bc;\"><b>\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13<\/b><\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e44\u0e1b\u0e01\u0e25\u0e31\u0e1a (\u0e01\u0e17\u0e21.- \u0e2e\u0e32\u0e19\u0e2d\u0e22) \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 1,XXX \u0e1a\u0e32\u0e17 <\/span><i><span style=\"font-weight: 400;\">(\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e14\u0e49\u0e27\u0e22 )<\/span><\/i><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 XXX \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e37\u0e19 \u0e16\u0e49\u0e32\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e14\u0e35\u0e01\u0e47\u0e41\u0e1e\u0e07\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e48\u0e2d\u0e22<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e1a\u0e32\u0e07\u0e04\u0e19\u0e40\u0e0a\u0e48\u0e32\u0e21\u0e2d\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e44\u0e0b\u0e04\u0e4c\u0e01\u0e47\u0e21\u0e35 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e02\u0e31\u0e1a\u0e44\u0e21\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e25\u0e35\u0e48\u0e22\u0e07\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e04\u0e23\u0e31\u0e1a<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e14\u0e35 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e25\u0e07\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e2e\u0e32\u0e19\u0e2d\u0e22\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e19\u0e31\u0e48\u0e07\u0e23\u0e16\u0e1a\u0e31\u0e2a \u0e2b\u0e23\u0e37\u0e2d\u0e23\u0e16\u0e44\u0e1f\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e21\u0e38\u0e48\u0e07\u0e2a\u0e39\u0e48\u0e08\u0e38\u0e14\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e0b\u0e32\u0e1b\u0e32\u0e04\u0e23\u0e31\u0e1a \u0e41\u0e19\u0e30\u0e19\u0e33\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13\u0e43\u0e2b\u0e49\u0e14\u0e35 \u0e41\u0e25\u0e30\u0e41\u0e25\u0e01\u0e40\u0e07\u0e34\u0e19\u0e14\u0e2d\u0e07\u0e40\u0e27\u0e35\u0e22\u0e14\u0e19\u0e32\u0e21 (VND) \u0e14\u0e49\u0e27\u0e22\u0e19\u0e30<\/span><\/p>\n<h2><span style=\"color: #29579b;\"><b>4. \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e14\u0e39\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e02\u0e2d\u0e21\u0e17\u0e35\u0e48\u0e40\u0e2a\u0e35\u0e22\u0e21\u0e40\u0e23\u0e35\u0e22\u0e1a<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e07\u0e1a 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e2b\u0e19\u0e14\u0e35 ? \u0e04\u0e37\u0e2d \u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27<span style=\"color: #29579b;\"><strong>\u0e40\u0e2a\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e1a \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e2a\u0e35\u0e22\u0e21\u0e23\u0e32\u0e10 (Siem Reap)<\/strong> <\/span>\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e32\u0e07\u0e15\u0e30\u0e27\u0e31\u0e19\u0e15\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e23\u0e34\u0e21\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e32\u0e1a\u0e40\u0e02\u0e21\u0e23 \u0e2a\u0e16\u0e32\u0e19\u0e17\u0e35\u0e48\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e40\u0e25\u0e22\u0e25\u0e48\u0e30 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e21\u0e23\u0e14\u0e01\u0e42\u0e25\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e19\u0e04\u0e23\u0e27\u0e31\u0e14 \u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e19\u0e04\u0e23\u0e18\u0e21 \u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e2b\u0e34\u0e19 \u0e2d\u0e31\u0e07\u0e01\u0e2d\u0e23\u0e4c\u0e27\u0e31\u0e14 \u0e1b\u0e23\u0e32\u0e2a\u0e32\u0e17\u0e1a\u0e32\u0e22\u0e19 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e42\u0e15\u0e19\u0e40\u0e25\u0e2a\u0e32\u0e1a\u0e14\u0e39\u0e08\u0e23\u0e30\u0e40\u0e02\u0e49\u0e40\u0e1b\u0e47\u0e19 \u0e46 \u0e2f\u0e25\u0e2f \u0e41\u0e27\u0e30\u0e14\u0e39\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e02\u0e2d\u0e21\u0e41\u0e1a\u0e1a\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21\u0e43\u0e2b\u0e49\u0e1f\u0e34\u0e19\u0e2d\u0e38\u0e23\u0e32 \u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e1a\u0e34\u0e19\u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19 1 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e04\u0e23\u0e31\u0e1a\u0e1c\u0e21<\/span><br \/>\n<img class=\"alignnone size-full wp-image-8761\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-09.jpg\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\" width=\"871\" height=\"540\" \/><\/p>\n<h3><span style=\"color: #00d0bc;\"><b>\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13<\/b><\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e44\u0e1b\u0e01\u0e25\u0e31\u0e1a (\u0e01\u0e17\u0e21. - \u0e40\u0e2a\u0e35\u0e22\u0e21\u0e23\u0e32\u0e10) \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48 2,XXX \u0e1a\u0e32\u0e17 <\/span><i><span style=\"font-weight: 400;\">(\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e46 )<\/span><\/i><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 XXX \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e37\u0e19\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u0e41\u0e19\u0e30\u0e19\u0e33\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e2a\u0e35\u0e22\u0e21\u0e40\u0e23\u0e35\u0e22\u0e1a \u0e01\u0e31\u0e21\u0e1e\u0e39\u0e0a\u0e32\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e28\u0e23\u0e49\u0e2d\u0e19\u0e40\u0e2b\u0e19\u0e2d\u0e30\u0e2b\u0e19\u0e30 \u0e40\u0e23\u0e32\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e2b\u0e21\u0e27\u0e01 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e42\u0e25\u0e0a\u0e31\u0e48\u0e19\u0e01\u0e31\u0e19\u0e41\u0e14\u0e14 \u0e41\u0e25\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e43\u0e2b\u0e49\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e24\u0e14\u0e39\u0e1d\u0e19\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19\u0e16\u0e36\u0e07\u0e15\u0e38\u0e25\u0e32\u0e04\u0e21\u00a0<\/span><\/p>\n<h2><span style=\"color: #29579b;\"><b>5. \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e21\u0e32\u0e40\u0e25\u0e40\u0e0b\u0e35\u0e22 \u0e1e\u0e31\u0e01\u0e43\u0e08\u0e17\u0e35\u0e48\u0e01\u0e31\u0e27\u0e25\u0e32\u0e25\u0e31\u0e21\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u00a0<\/b><\/span><\/h2>\n<p><span style=\"color: #00d0bc;\"><i><span style=\"font-weight: 400;\">\u201c\u0e21\u0e32\u0e40\u0e25\u0e4a \u0e21\u0e32\u0e40\u0e25\u201d<\/span><\/i><\/span><span style=\"font-weight: 400;\"> \u0e2d\u0e35\u0e01\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 10,000 \u0e1a\u0e32\u0e17\u0e04\u0e37\u0e2d<strong><span style=\"color: #00d0bc;\"> \u201c\u0e01\u0e31\u0e27\u0e25\u0e32\u0e25\u0e31\u0e21\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u201d<\/span> <\/strong>\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e21\u0e32\u0e40\u0e25\u0e40\u0e0b\u0e35\u0e22 \u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2b\u0e25\u0e27\u0e07\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e17\u0e32\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e21\u0e32\u0e01 \u0e46 \u0e40\u0e25\u0e22\u0e04\u0e48\u0e30 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e47\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e25\u0e31\u0e27\u0e2b\u0e25\u0e07 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e1a\u0e01\u0e40\u0e1b\u0e49\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e34\u0e25\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e2a\u0e1a\u0e32\u0e22 \u0e1e\u0e34\u0e01\u0e31\u0e14\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49 \u0e04\u0e37\u0e2d \u0e15\u0e36\u0e01\u0e41\u0e1d\u0e14\u0e1b\u0e34\u0e42\u0e15\u0e23\u0e19\u0e32\u0e2a \u0e41\u0e25\u0e19\u0e14\u0e4c\u0e21\u0e32\u0e23\u0e4c\u0e04\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e21\u0e32\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e21\u0e32\u0e44\u0e21\u0e48\u0e16\u0e36\u0e07\u0e21\u0e32\u0e40\u0e25\u0e40\u0e14\u0e49\u0e2d \u0e41\u0e27\u0e30\u0e16\u0e48\u0e32\u0e22\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e21\u0e21\u0e31\u0e2a\u0e22\u0e34\u0e14\u0e1b\u0e39\u0e15\u0e23\u0e32\u0e08\u0e32\u0e22\u0e32\u0e2a\u0e35\u0e0a\u0e21\u0e1e\u0e39\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e34\u0e21\u0e17\u0e30\u0e40\u0e25\u0e2a\u0e32\u0e1a \u0e0a\u0e21\u0e2a\u0e38\u0e40\u0e2b\u0e23\u0e48\u0e32\u0e2a\u0e35\u0e19\u0e49\u0e33\u0e40\u0e07\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e21\u0e31\u0e2a\u0e22\u0e34\u0e14\u0e2a\u0e38\u0e25\u0e15\u0e48\u0e32\u0e19 \u0e0b\u0e32\u0e25\u0e32\u0e2e\u0e38\u0e14\u0e14\u0e35\u0e19 \u0e2d\u0e31\u0e1a\u0e14\u0e38\u0e25 \u0e2d\u0e32\u0e0b\u0e34\u0e2a \u0e0a\u0e32\u0e2b\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e01\u0e47\u0e19\u0e15\u0e34\u0e49\u0e07\u0e44\u0e2e\u0e41\u0e25\u0e19\u0e14\u0e4c\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e1a\u0e19\u0e22\u0e2d\u0e14\u0e40\u0e02\u0e32\u0e2a\u0e39\u0e07 2,000 \u0e40\u0e21\u0e15\u0e23\u0e08\u0e32\u0e01\u0e19\u0e49\u0e33\u0e17\u0e30\u0e40\u0e25 \u0e40\u0e01\u0e4b \u0e46 \u0e19\u0e31\u0e48\u0e07\u0e23\u0e16\u0e40\u0e1e\u0e35\u0e22\u0e07 1 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07\u0e01\u0e47\u0e16\u0e36\u0e07\u0e04\u0e23\u0e31\u0e1a<\/span><br \/>\n<img class=\"alignnone size-full wp-image-8762\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-08.jpg\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\" width=\"871\" height=\"540\" \/><\/p>\n<h3><span style=\"color: #00d0bc;\"><b>\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13<\/b><\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e44\u0e1b\u0e01\u0e25\u0e31\u0e1a (\u0e01\u0e17\u0e21. - \u0e01\u0e31\u0e27\u0e25\u0e32\u0e25\u0e31\u0e21\u0e40\u0e1b\u0e2d\u0e23\u0e4c) \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48 2,XXX \u0e1a\u0e32\u0e17 <\/span><i><span style=\"font-weight: 400;\">(\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e46 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1a\u0e34\u0e19\u0e14\u0e49\u0e27\u0e22)<\/span><\/i><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19 XXX \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e37\u0e19\u00a0<\/span><\/li>\n<\/ul>\n<h2><span style=\"color: #29579b;\"><b>6. \u0e1a\u0e38\u0e01\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c\u0e14\u0e39\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e44\u0e25\u0e2d\u0e2d\u0e19<\/b><\/span><\/h2>\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e42\u0e25\u0e40\u0e04\u0e0a\u0e31\u0e48\u0e19\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e17\u0e35\u0e48\u0e08\u0e30<span style=\"color: #00d0bc;\"><strong><em>\u0e41\u0e1a\u0e47\u0e04\u0e41\u0e1e\u0e04\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e14\u0e49\u0e27\u0e22\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07<\/em><\/strong><\/span> \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e32\u0e21\u0e2b\u0e32\u0e40\u0e21\u0e2d\u0e23\u0e4c\u0e44\u0e25\u0e2d\u0e2d\u0e19\u0e40\u0e08\u0e49\u0e32\u0e2a\u0e34\u0e07\u0e2b\u0e4c\u0e42\u0e15\u0e1e\u0e48\u0e19\u0e19\u0e49\u0e33 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e19\u0e41\u0e27\u0e30\u0e14\u0e39\u0e19\u0e49\u0e33\u0e15\u0e01\u0e17\u0e35\u0e48\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e02\u0e36\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e32\u0e07\u0e08\u0e35\u0e40\u0e27\u0e25 \u0e0a\u0e32\u0e07\u0e07\u0e35\u0e17\u0e35\u0e48\u0e2d\u0e25\u0e31\u0e07\u0e01\u0e32\u0e23\u0e14\u0e32\u0e27\u0e25\u0e49\u0e32\u0e19\u0e14\u0e27\u0e07\u0e2a\u0e38\u0e14 \u0e46 \u0e2b\u0e32\u0e01\u0e02\u0e22\u0e31\u0e1a\u0e43\u0e01\u0e25\u0e49 \u0e46 \u0e19\u0e49\u0e33\u0e15\u0e01\u0e40\u0e23\u0e32\u0e08\u0e30\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e16\u0e36\u0e07\u0e25\u0e30\u0e2d\u0e2d\u0e07\u0e19\u0e49\u0e33\u0e17\u0e35\u0e48\u0e01\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e1b\u0e30\u0e17\u0e30\u0e2a\u0e39\u0e48\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e41\u0e1a\u0e1a\u0e15\u0e23\u0e07 \u0e46 \u0e40\u0e2d\u0e37\u0e49\u0e2d \u2026. \u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e40\u0e14\u0e34\u0e19\u0e0a\u0e49\u0e2d\u0e1b\u0e17\u0e35\u0e48\u0e2b\u0e49\u0e32\u0e07\u0e15\u0e34\u0e14\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19\u0e0a\u0e32\u0e07\u0e07\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e19\u0e35\u0e49\u0e01\u0e47\u0e2b\u0e21\u0e14\u0e40\u0e27\u0e25\u0e32\u0e17\u0e31\u0e49\u0e07\u0e27\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e08\u0e49\u0e32 \u0e15\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2a\u0e27\u0e19\u0e2a\u0e19\u0e38\u0e01\u0e22\u0e39\u0e19\u0e34\u0e40\u0e27\u0e2d\u0e23\u0e4c\u0e41\u0e0b\u0e25\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e41\u0e25\u0e30\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e01\u0e32\u0e23\u0e4c\u0e40\u0e14\u0e49\u0e19\u0e1a\u0e32\u0e22\u0e40\u0e14\u0e2d\u0e30\u0e40\u0e1a\u0e22\u0e4c (Garden by the bay) \u0e14\u0e39\u0e07\u0e32\u0e19\u0e41\u0e2a\u0e14\u0e07\u0e41\u0e2a\u0e07\u0e2a\u0e35\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49 Supertree Grove \u0e15\u0e32\u0e21\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e17\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e2d\u0e37\u0e48\u0e19 \u0e46 \u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e25\u0e31\u0e27\u0e2b\u0e25\u0e07\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e14\u0e35\u0e21\u0e32\u0e01<\/span><br \/>\n<img class=\"alignnone size-full wp-image-8763\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-07.jpg\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\" width=\"871\" height=\"540\" \/><\/p>\n<h3><span style=\"color: #00d0bc;\"><b>\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13<\/b><\/span><\/h3>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e44\u0e1b\u0e01\u0e25\u0e31\u0e1a (\u0e01\u0e17\u0e21.-\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c) \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48 2,XXX \u0e1a\u0e32\u0e17 <\/span><i><span style=\"font-weight: 400;\">(\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e19\u0e31\u0e49\u0e19 \u0e46 )<\/span><\/i><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e2b\u0e32\u0e01\u0e1e\u0e31\u0e01\u0e2a\u0e1a\u0e32\u0e22 \u0e46 \u0e43\u0e01\u0e25\u0e49\u0e23\u0e16\u0e44\u0e1f\u0e43\u0e15\u0e49\u0e14\u0e34\u0e19 MRT \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e04\u0e48\u0e32\u0e2b\u0e49\u0e2d\u0e07\u0e1e\u0e31\u0e01 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e17\u0e35\u0e48 X,XXX \u0e1a\u0e32\u0e17\u0e15\u0e48\u0e2d\u0e04\u0e37\u0e19\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e01\u0e32\u0e23\u0e01\u0e34\u0e19\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e2a\u0e39\u0e07\u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e04\u0e48\u0e32\u0e19\u0e49\u0e33\u0e40\u0e1b\u0e25\u0e48\u0e32\u0e40\u0e09\u0e25\u0e35\u0e48\u0e22\u0e02\u0e27\u0e14\u0e25\u0e30 $2\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e1a\u0e31\u0e15\u0e23 EZ Link \u0e44\u0e27\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 $12 = 264 \u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e17\u0e31\u0e49\u0e07\u0e17\u0e23\u0e34\u0e1b \u0e42\u0e14\u0e22\u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e48\u0e32\u0e21\u0e31\u0e14\u0e08\u0e33\u0e1a\u0e31\u0e15\u0e23 $5 \u0e43\u0e0a\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e14\u0e49 $7 \u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e15\u0e34\u0e21\u0e40\u0e07\u0e34\u0e19\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 $10 \u0e01\u0e47\u0e14\u0e35\u0e04\u0e23\u0e31\u0e1a\u00a0 (\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a 22 \u0e1a\u0e32\u0e17 = 1 \u0e14\u0e2d\u0e25\u0e25\u0e32\u0e23\u0e4c\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c) \u0e1a\u0e31\u0e15\u0e23 EZ Link \u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49 5 \u0e1b\u0e35<\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">\u0e2a\u0e19\u0e43\u0e08\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27!! \u0e08\u0e07\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e17\u0e23\u0e34\u0e1b \u0e41\u0e1e\u0e04\u0e01\u0e23\u0e30\u0e40\u0e1b\u0e4b\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e01\u0e31\u0e1a\u0e2d\u0e48\u0e32\u0e19\u0e1a\u0e17\u0e04\u0e27\u0e32\u0e21<\/span><span style=\"color: #29579b;\"><a style=\"color: #29579b;\" href=\"https:\/\/www.bolttech.co.th\/blog\/%e0%b8%81%e0%b8%a3%e0%b8%ad%e0%b8%81%e0%b9%83%e0%b8%9a%e0%b8%95%e0%b8%a1%e0%b8%aa%e0%b8%b4%e0%b8%87%e0%b8%84%e0%b9%82%e0%b8%9b%e0%b8%a3%e0%b9%8c\"><b><i>\u0e01\u0e23\u0e2d\u0e01\u0e43\u0e1a \u0e15\u0e21. \u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0b\u0e35\u0e22\u0e19 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e32<\/i><\/b><\/a><\/span><span style=\"font-weight: 400;\">\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e41\u0e1f\u0e23\u0e07\u0e04\u0e4c\u0e40\u0e2d\u0e07\u0e40\u0e1e\u0e34\u0e48\u0e07\u0e44\u0e1b\u0e21\u0e32\u0e25\u0e48\u0e30 \u0e2d\u0e34\u0e2d\u0e34<\/span><\/p>\n<blockquote><p><span style=\"color: #29579b;\"><b>\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e07\u0e1a\u0e49\u0e32\u0e07\u0e44\u0e14\u0e49\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e2b\u0e23\u0e37\u0e2d\u0e22\u0e31\u0e07 ?<\/b><\/span><\/p><\/blockquote>\n<p><span style=\"font-weight: 400;\">\u0e41\u0e25\u0e30\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14\u0e19\u0e35\u0e49\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19 6 \u0e1e\u0e34\u0e01\u0e31\u0e14\u0e43\u0e19 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e01\u0e25\u0e49\u0e44\u0e17\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e14\u0e49\u0e07\u0e1a\u0e44\u0e21\u0e48\u0e1a\u0e32\u0e19\u0e1b\u0e25\u0e32\u0e22 \u0e14\u0e35\u0e15\u0e48\u0e2d\u0e43\u0e08\u0e04\u0e19\u0e0a\u0e2d\u0e1a\u0e41\u0e1a\u0e47\u0e04\u0e41\u0e1e\u0e04\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22 \u0e40\u0e2d\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e48\u0e32<span style=\"color: #29579b;\"><em><strong> \u0e21\u0e35\u0e07\u0e1a 10,000 \u0e1a\u0e32\u0e17\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e2d\u0e1a\u0e40\u0e25\u0e22\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a<\/strong><\/em><\/span> \u0e41\u0e15\u0e48\u0e2d\u0e22\u0e48\u0e32\u0e25\u0e37\u0e21\u0e0b\u0e37\u0e49\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e15\u0e34\u0e14\u0e15\u0e31\u0e27\u0e44\u0e27\u0e49\u0e14\u0e49\u0e27\u0e22\u0e19\u0e30 \u0e40\u0e1c\u0e37\u0e48\u0e2d\u0e21\u0e35\u0e40\u0e2b\u0e15\u0e38\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e44\u0e21\u0e48\u0e04\u0e32\u0e14\u0e1d\u0e31\u0e19\u0e02\u0e36\u0e49\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e08\u0e30\u0e44\u0e14\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e14\u0e39\u0e41\u0e25\u0e04\u0e38\u0e13\u0e44\u0e14\u0e49 \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e23\u0e32\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48\u0e21\u0e35\u0e17\u0e23\u0e34\u0e1b\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e01\u0e47\u0e44\u0e14\u0e49\u0e04\u0e23\u0e31\u0e1a \u0e1b\u0e23\u0e30\u0e2b\u0e22\u0e31\u0e14\u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e0b\u0e1f\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e35\u0e01\u0e40\u0e22\u0e2d\u0e30<br \/>\nContent by Butter Cutter<br \/>\n<\/span><br \/>\n<a href=\"https:\/\/www.bolttech.co.th\/%E0%B8%9B%E0%B8%A3%E0%B8%B0%E0%B8%81%E0%B8%B1%E0%B8%99%E0%B8%81%E0%B8%B2%E0%B8%A3%E0%B9%80%E0%B8%94%E0%B8%B4%E0%B8%99%E0%B8%97%E0%B8%B2%E0%B8%87\" target=\"_blank\" rel=\"noopener\"><img class=\"alignnone wp-image-8760\" src=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-10.jpg\" alt=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\" width=\"871\" height=\"300\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e2b\u0e32\u0e41\u0e1e\u0e25\u0e19\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e41\u0e25\u0e30\u0e21\u0e35\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22!! \u0e1a\u0e19\u0e42\u0e08\u0e17\u0e22\u0e4c\u0e17\u0e35\u0e48\u0e27\u0e48\u0e32 \u201c\u0e21\u0e35\u0e07\u0e1a 10,000 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e44\u0e2b\u0e19\u0e14\u0e35?\u201d \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e43\u0e2b\u0e49\u0e2a\u0e32\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e42\u0e19\u0e2a\u0e19\u0e42\u0e19\u0e41\u0e04\u0e23\u0e4c\u0e27\u0e48\u0e32 \u201c\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e17 \u0e1c\u0e39\u0e49\u0e40\u0e17\u0e41\u0e25\u0e49\u0e27\u0e44\u0e07 \u0e40\u0e23\u0e32\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e47\u0e44\u0e14\u0e49!\u201d \u0e40\u0e1e\u0e19\u0e01\u0e27\u0e34\u0e19\u0e41\u0e1f\u0e23\u0e07\u0e04\u0e4c\u0e21\u0e35 6 \u0e1e\u0e34\u0e01\u0e31\u0e14\u0e43\u0e19 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e21\u0e32\u0e41\u0e19\u0e30\u0e19\u0e33\u0e04\u0e23\u0e49\u0e32\u0e1a\u0e1a\u0e1a\u00a0 1. \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e22\u0e48\u0e32\u0e07\u0e01\u0e38\u0e49\u0e07 \u0e1a\u0e38\u0e01\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e1e\u0e21\u0e48\u0e32\u00a0 \u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e2b\u0e19\u0e14\u0e35\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e1f\u0e23\u0e35\u0e27\u0e35\u0e0b\u0e48\u0e32\u0e04\u0e19\u0e44\u0e17<\/p>\n","protected":false},"author":20,"featured_media":8769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[2062],"tags":[1029,1084,1072,1778,1779,1087,1096],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.0 (Yoast SEO v20.5) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e21\u0e35\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 6 \u0e1e\u0e34\u0e01\u0e31\u0e14 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e2a\u0e34 ?<\/title>\n<meta name=\"description\" content=\"\u0e42\u0e14\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e17\u0e17\u0e23\u0e34\u0e1b \u0e42\u0e14\u0e19\u0e41\u0e1f\u0e19\u0e40\u0e17\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e22\u0e32\u0e01\u0e25\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e14\u0e35\u0e2b\u0e19\u0e2d \u0e16\u0e49\u0e32\u0e21\u0e35\u0e07\u0e1a 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e1a\u0e32\u0e17 \u0e2d\u0e48\u0e32\u0e19\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bolttech.co.th\/blog\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e21\u0e35\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 6 \u0e1e\u0e34\u0e01\u0e31\u0e14 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e2a\u0e34 ?\" \/>\n<meta property=\"og:description\" content=\"\u0e42\u0e14\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e17\u0e17\u0e23\u0e34\u0e1b \u0e42\u0e14\u0e19\u0e41\u0e1f\u0e19\u0e40\u0e17\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e22\u0e32\u0e01\u0e25\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e14\u0e35\u0e2b\u0e19\u0e2d \u0e16\u0e49\u0e32\u0e21\u0e35\u0e07\u0e1a 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e1a\u0e32\u0e17 \u0e2d\u0e48\u0e32\u0e19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bolttech.co.th\/blog\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\" \/>\n<meta property=\"og:site_name\" content=\"Bolttech Blog - News &amp; Updates\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-10T03:12:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-02.jpg\" \/>\n<meta name=\"author\" content=\"Butter Cutter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-03.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@bolttechTH\" \/>\n<meta name=\"twitter:site\" content=\"@bolttechTH\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Butter Cutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\",\"url\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\",\"name\":\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e21\u0e35\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 6 \u0e1e\u0e34\u0e01\u0e31\u0e14 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e2a\u0e34 ?\",\"isPartOf\":{\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#website\"},\"datePublished\":\"2019-11-10T03:12:55+00:00\",\"dateModified\":\"2019-11-10T03:12:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9\"},\"description\":\"\u0e42\u0e14\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e17\u0e17\u0e23\u0e34\u0e1b \u0e42\u0e14\u0e19\u0e41\u0e1f\u0e19\u0e40\u0e17\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e22\u0e32\u0e01\u0e25\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e14\u0e35\u0e2b\u0e19\u0e2d \u0e16\u0e49\u0e32\u0e21\u0e35\u0e07\u0e1a 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e1a\u0e32\u0e17 \u0e2d\u0e48\u0e32\u0e19\",\"breadcrumb\":{\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.bolttech.co.th\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e21\u0e35\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 6 \u0e1e\u0e34\u0e01\u0e31\u0e14 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e2a\u0e34 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#website\",\"url\":\"https:\/\/www.bolttech.co.th\/blog\/\",\"name\":\"Bolttech Blog - News &amp; Updates\",\"description\":\"Bolttech Blog - News &amp; Updates\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.bolttech.co.th\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"th\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9\",\"name\":\"Butter Cutter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g\",\"caption\":\"Butter Cutter\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e21\u0e35\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 6 \u0e1e\u0e34\u0e01\u0e31\u0e14 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e2a\u0e34 ?","description":"\u0e42\u0e14\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e17\u0e17\u0e23\u0e34\u0e1b \u0e42\u0e14\u0e19\u0e41\u0e1f\u0e19\u0e40\u0e17\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e22\u0e32\u0e01\u0e25\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e14\u0e35\u0e2b\u0e19\u0e2d \u0e16\u0e49\u0e32\u0e21\u0e35\u0e07\u0e1a 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e1a\u0e32\u0e17 \u0e2d\u0e48\u0e32\u0e19","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bolttech.co.th\/blog\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22","og_locale":"th_TH","og_type":"article","og_title":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e21\u0e35\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 6 \u0e1e\u0e34\u0e01\u0e31\u0e14 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e2a\u0e34 ?","og_description":"\u0e42\u0e14\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e17\u0e17\u0e23\u0e34\u0e1b \u0e42\u0e14\u0e19\u0e41\u0e1f\u0e19\u0e40\u0e17\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e22\u0e32\u0e01\u0e25\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e14\u0e35\u0e2b\u0e19\u0e2d \u0e16\u0e49\u0e32\u0e21\u0e35\u0e07\u0e1a 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e1a\u0e32\u0e17 \u0e2d\u0e48\u0e32\u0e19","og_url":"https:\/\/www.bolttech.co.th\/blog\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22","og_site_name":"Bolttech Blog - News &amp; Updates","article_published_time":"2019-11-10T03:12:55+00:00","og_image":[{"url":"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-02.jpg"}],"author":"Butter Cutter","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.bolttech.co.th\/blog\/wp-content\/uploads\/2019\/10\/\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27-03.jpg","twitter_creator":"@bolttechTH","twitter_site":"@bolttechTH","twitter_misc":{"Written by":"Butter Cutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2","url":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2","name":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e21\u0e35\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 6 \u0e1e\u0e34\u0e01\u0e31\u0e14 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e2a\u0e34 ?","isPartOf":{"@id":"https:\/\/www.bolttech.co.th\/blog\/#website"},"datePublished":"2019-11-10T03:12:55+00:00","dateModified":"2019-11-10T03:12:55+00:00","author":{"@id":"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9"},"description":"\u0e42\u0e14\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e40\u0e17\u0e17\u0e23\u0e34\u0e1b \u0e42\u0e14\u0e19\u0e41\u0e1f\u0e19\u0e40\u0e17\u0e17\u0e31\u0e27\u0e23\u0e4c \u0e2d\u0e22\u0e32\u0e01\u0e25\u0e2d\u0e07\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22 \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e07\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e14\u0e35\u0e2b\u0e19\u0e2d \u0e16\u0e49\u0e32\u0e21\u0e35\u0e07\u0e1a 1 \u0e2b\u0e21\u0e37\u0e48\u0e19\u0e1a\u0e32\u0e17 \u0e2d\u0e48\u0e32\u0e19","breadcrumb":{"@id":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.bolttech.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%95%e0%b9%88%e0%b8%b2%e0%b8%87%e0%b8%9b%e0%b8%a3%e0%b8%b0%e0%b9%80%e0%b8%97%e0%b8%a8%e0%b8%84%e0%b8%99%e0%b9%80%e0%b8%94%e0%b8%b5%e0%b8%a2%e0%b8%a7%e0%b8%87%e0%b8%9a%e0%b8%99%e0%b9%89%e0%b8%ad%e0%b8%a2#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.bolttech.co.th\/blog"},{"@type":"ListItem","position":2,"name":"\u0e40\u0e17\u0e35\u0e48\u0e22\u0e27\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e21\u0e35\u0e07\u0e1a\u0e2b\u0e21\u0e37\u0e48\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e40\u0e17\u0e35\u0e48\u0e22\u0e27 6 \u0e1e\u0e34\u0e01\u0e31\u0e14 6 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e19\u0e35\u0e49\u0e2a\u0e34 ?"}]},{"@type":"WebSite","@id":"https:\/\/www.bolttech.co.th\/blog\/#website","url":"https:\/\/www.bolttech.co.th\/blog\/","name":"Bolttech Blog - News &amp; Updates","description":"Bolttech Blog - News &amp; Updates","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bolttech.co.th\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"th"},{"@type":"Person","@id":"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/7bae194b256a71cb1d51191a3ebc65d9","name":"Butter Cutter","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.bolttech.co.th\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc9334891c0adc1e20a99625e3b30195?s=96&d=mm&r=g","caption":"Butter Cutter"}}]}},"_links":{"self":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts\/8759"}],"collection":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/comments?post=8759"}],"version-history":[{"count":0,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/posts\/8759\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/media\/8769"}],"wp:attachment":[{"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/media?parent=8759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/categories?post=8759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bolttech.co.th\/blog\/wp-json\/wp\/v2\/tags?post=8759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}